{"text_format":"1","workbook":"xlsx","n_sheets":9,"sheets":["Profit & Loss","Quarters","Balance Sheet","Cash Flow","Customization","Data Sheet","KeyMetrics","Charts","Forecast"],"not_rendered":{"charts":38,"images":1,"macros":1,"external_links":1,"defined_names":4,"comments":2,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"Profit & Loss","index":0,"n_rows":25,"n_cols":14,"rows_kept":25,"cut":false,"hidden":true,"merged":[]}
[{"$f":"'Data Sheet'!B1","v":"BHARAT RASAYAN LTD"},null,null,null,null,null,null,{"$f":"UPDATE","v":""},null,null,null,null,"SCREENER.IN"]
[]
["Narration",{"$f":"'Data Sheet'!B16","v":"2009-03-31"},{"$f":"'Data Sheet'!C16","v":"2010-03-31"},{"$f":"'Data Sheet'!D16","v":"2011-03-31"},{"$f":"'Data Sheet'!E16","v":"2012-03-31"},{"$f":"'Data Sheet'!F16","v":"2013-03-31"},{"$f":"'Data Sheet'!G16","v":"2014-03-31"},{"$f":"'Data Sheet'!H16","v":"2015-03-31"},{"$f":"'Data Sheet'!I16","v":"2016-03-31"},{"$f":"'Data Sheet'!J16","v":"2017-03-31"},{"$f":"'Data Sheet'!K16","v":"2018-03-31"},"Trailing","Best Case","Worst Case"]
["Sales",{"$f":"'Data Sheet'!B17","v":102.94},{"$f":"'Data Sheet'!C17","v":99.22},{"$f":"'Data Sheet'!D17","v":93.63},{"$f":"'Data Sheet'!E17","v":141.94999999999999},{"$f":"'Data Sheet'!F17","v":185.19},{"$f":"'Data Sheet'!G17","v":360.28},{"$f":"'Data Sheet'!H17","v":437.69},{"$f":"'Data Sheet'!I17","v":451.21},{"$f":"'Data Sheet'!J17","v":618.5},{"$f":"'Data Sheet'!K17","v":792.33},{"$f":"SUM(Quarters!H4:K4)","v":992.18000000000006},{"$f":"$K4+M23*K4","v":1015.0150831042847},{"$f":"$K4+N23*L4","v":1009.3652815867935}]
["Expenses",{"$f":"SUM('Data Sheet'!B18,'Data Sheet'!B20:B24, -1*'Data Sheet'!B19)","v":96.57},{"$f":"SUM('Data Sheet'!C18,'Data Sheet'!C20:C24, -1*'Data Sheet'!C19)","v":92.810000000000016},{"$f":"SUM('Data Sheet'!D18,'Data Sheet'!D20:D24, -1*'Data Sheet'!D19)","v":87.08},{"$f":"SUM('Data Sheet'!E18,'Data Sheet'!E20:E24, -1*'Data Sheet'!E19)","v":125.26000000000002},{"$f":"SUM('Data Sheet'!F18,'Data Sheet'!F20:F24, -1*'Data Sheet'!F19)","v":159.46},{"$f":"SUM('Data Sheet'!G18,'Data Sheet'!G20:G24, -1*'Data Sheet'!G19)","v":296.52},{"$f":"SUM('Data Sheet'!H18,'Data Sheet'!H20:H24, -1*'Data Sheet'!H19)","v":355.28999999999996},{"$f":"SUM('Data Sheet'!I18,'Data Sheet'!I20:I24, -1*'Data Sheet'!I19)","v":370.04},{"$f":"SUM('Data Sheet'!J18,'Data Sheet'!J20:J24, -1*'Data Sheet'!J19)","v":507.87},{"$f":"SUM('Data Sheet'!K18,'Data Sheet'!K20:K24, -1*'Data Sheet'!K19)","v":638.91999999999996},{"$f":"SUM(Quarters!H5:K5)","v":805.08},{"$f":"M4-M6","v":823.60896521356767},839.30426172310808]
["Operating Profit",{"$f":"B4-B5","v":6.3700000000000045},{"$f":"C4-C5","v":6.4099999999999824},6.5499999999999972,16.689999999999969,25.72999999999999,63.759999999999991,82.400000000000034,81.169999999999959,110.63,153.41000000000008,{"$f":"SUM(Quarters!H6:K6)","v":187.1},{"$f":"M4*M24","v":191.40611789071704},{"$f":"N4*N24","v":170.06101986368537}]
["Other Income",{"$f":"'Data Sheet'!B25","v":4.12},{"$f":"'Data Sheet'!C25","v":3.65},{"$f":"'Data Sheet'!D25","v":3.56},{"$f":"'Data Sheet'!E25","v":-0.28999999999999998},{"$f":"'Data Sheet'!F25","v":0.18},{"$f":"'Data Sheet'!G25","v":0.64},{"$f":"'Data Sheet'!H25","v":0.86},{"$f":"'Data Sheet'!I25","v":0.6},{"$f":"'Data Sheet'!J25","v":1.96},{"$f":"'Data Sheet'!K25","v":9.7899999999999991},{"$f":"SUM(Quarters!H7:K7)","v":0.74999999999999978},0,0]
["Depreciation",{"$f":"'Data Sheet'!B26","v":0.93},{"$f":"'Data Sheet'!C26","v":0.88},{"$f":"'Data Sheet'!D26","v":1.81},{"$f":"'Data Sheet'!E26","v":1.62},{"$f":"'Data Sheet'!F26","v":6.88},{"$f":"'Data Sheet'!G26","v":17.829999999999998},{"$f":"'Data Sheet'!H26","v":17.73},{"$f":"'Data Sheet'!I26","v":17.03},{"$f":"'Data Sheet'!J26","v":16.43},{"$f":"'Data Sheet'!K26","v":16.420000000000002},{"$f":"SUM(Quarters!H8:K8)","v":16.89},{"$f":"+$L8","v":16.89},{"$f":"+$L8","v":16.89}]
["Interest",{"$f":"'Data Sheet'!B27","v":0.83},{"$f":"'Data Sheet'!C27","v":0.49},{"$f":"'Data Sheet'!D27","v":0.27},{"$f":"'Data Sheet'!E27","v":1.06},{"$f":"'Data Sheet'!F27","v":4.96},{"$f":"'Data Sheet'!G27","v":16.559999999999999},{"$f":"'Data Sheet'!H27","v":17.5},{"$f":"'Data Sheet'!I27","v":13.24},{"$f":"'Data Sheet'!J27","v":12.45},{"$f":"'Data Sheet'!K27","v":11.17},{"$f":"SUM(Quarters!H9:K9)","v":15.82},{"$f":"+$L9","v":15.82},{"$f":"+$L9","v":15.82}]
["Profit before tax",{"$f":"'Data Sheet'!B28","v":8.77},{"$f":"'Data Sheet'!C28","v":8.69},{"$f":"'Data Sheet'!D28","v":8.0299999999999994},{"$f":"'Data Sheet'!E28","v":13.72},{"$f":"'Data Sheet'!F28","v":14.11},{"$f":"'Data Sheet'!G28","v":30.07},{"$f":"'Data Sheet'!H28","v":48.06},{"$f":"'Data Sheet'!I28","v":51.56},{"$f":"'Data Sheet'!J28","v":83.92},{"$f":"'Data Sheet'!K28","v":135.62},{"$f":"SUM(Quarters!H10:K10)","v":155.13999999999999},{"$f":"M6+M7-SUM(M8:M9)","v":158.69611789071703},{"$f":"N6+N7-SUM(N8:N9)","v":137.35101986368537}]
["Tax",{"$f":"'Data Sheet'!B29","v":3.6},{"$f":"'Data Sheet'!C29","v":2.88},{"$f":"'Data Sheet'!D29","v":2.14},{"$f":"'Data Sheet'!E29","v":3.89},{"$f":"'Data Sheet'!F29","v":4.53},{"$f":"'Data Sheet'!G29","v":9.91},{"$f":"'Data Sheet'!H29","v":16.309999999999999},{"$f":"'Data Sheet'!I29","v":17.68},{"$f":"'Data Sheet'!J29","v":29.39},{"$f":"'Data Sheet'!K29","v":37.31},{"$f":"SUM(Quarters!H11:K11)","v":43.609999999999992},{"$f":"IF($L10>0,$L11/$L10,0)","v":0.28110094108547118},{"$f":"IF($L10>0,$L11/$L10,0)","v":0.28110094108547118}]
["Net profit",{"$f":"'Data Sheet'!B30","v":5.17},{"$f":"'Data Sheet'!C30","v":5.81},{"$f":"'Data Sheet'!D30","v":5.89},{"$f":"'Data Sheet'!E30","v":9.83},{"$f":"'Data Sheet'!F30","v":9.59},{"$f":"'Data Sheet'!G30","v":20.149999999999999},{"$f":"'Data Sheet'!H30","v":31.75},{"$f":"'Data Sheet'!I30","v":33.880000000000003},{"$f":"'Data Sheet'!J30","v":54.53},{"$f":"'Data Sheet'!K30","v":98.31},{"$f":"SUM(Quarters!H12:K12)","v":111.53},{"$f":"M10-M11*M10","v":114.08648980502559},{"$f":"N10-N11*N10","v":98.741518920954164}]
["EPS",{"$f":"IF('Data Sheet'!B93>0,B12/'Data Sheet'!B93,0)","v":12.168313429393185},{"$f":"IF('Data Sheet'!C93>0,C12/'Data Sheet'!C93,0)","v":13.674642364559846},{"$f":"IF('Data Sheet'!D93>0,D12/'Data Sheet'!D93,0)","v":13.862933481455679},{"$f":"IF('Data Sheet'!E93>0,E12/'Data Sheet'!E93,0)","v":23.13627098857544},{"$f":"IF('Data Sheet'!F93>0,F12/'Data Sheet'!F93,0)","v":22.571397637887941},{"$f":"IF('Data Sheet'!G93>0,G12/'Data Sheet'!G93,0)","v":47.425825068137847},{"$f":"IF('Data Sheet'!H93>0,H12/'Data Sheet'!H93,0)","v":74.728037018033589},{"$f":"IF('Data Sheet'!I93>0,I12/'Data Sheet'!I93,0)","v":79.741288005385144},{"$f":"IF('Data Sheet'!J93>0,J12/'Data Sheet'!J93,0)","v":128.34393255412195},{"$f":"IF('Data Sheet'!K93>0,K12/'Data Sheet'!K93,0)","v":231.38624627536637},{"$f":"IF('Data Sheet'!$B6>0,'Profit & Loss'!L12/'Data Sheet'!$B6,0)","v":262.42315366860822},{"$f":"IF('Data Sheet'!$B6>0,'Profit & Loss'!M12/'Data Sheet'!$B6,0)","v":268.43841518529848},{"$f":"IF('Data Sheet'!$B6>0,'Profit & Loss'!N12/'Data Sheet'!$B6,0)","v":232.33265303743693}]
["Price to earning",{"$f":"IF(B15>0,B15/B13,\"\")","v":3.8906938315411987},{"$f":"IF(C15>0,C15/C13,\"\")","v":6.0542716798623069},6.4540362340831914,5.747790215012003,5.7041217413972882,6.8428838408976675,11.713441633543306,12.144256861446751,23.330004110146266,21.668170635489346,{"$f":"IF(L13>0,L15/L13,0)","v":15.655249708598584},{"$f":"M25","v":18.199420328920237},{"$f":"N25","v":10.836810953819809}]
["Price",{"$f":"'Data Sheet'!B90","v":47.343181999999999},{"$f":"'Data Sheet'!C90","v":82.79},{"$f":"'Data Sheet'!D90","v":89.471874999999997},{"$f":"'Data Sheet'!E90","v":132.98243199999999},{"$f":"'Data Sheet'!F90","v":128.75},{"$f":"'Data Sheet'!G90","v":324.52941199999998},{"$f":"'Data Sheet'!H90","v":875.32249999999999},{"$f":"'Data Sheet'!I90","v":968.398684},{"$f":"'Data Sheet'!J90","v":2994.2644740000001},{"$f":"'Data Sheet'!K90","v":5013.7166669999997},{"$f":"'Data Sheet'!B8","v":4108.3},{"$f":"M13*M14","v":4885.423550386452},{"$f":"N13*N14","v":2517.7450393661134}]
[]
["RATIOS:"]
["Dividend Payout",{"$f":"IF('Data Sheet'!B30>0, 'Data Sheet'!B31/'Data Sheet'!B30, 0)","v":8.1237911025145063E-2},{"$f":"IF('Data Sheet'!C30>0, 'Data Sheet'!C31/'Data Sheet'!C30, 0)","v":0.13253012048192772},{"$f":"IF('Data Sheet'!D30>0, 'Data Sheet'!D31/'Data Sheet'!D30, 0)","v":8.6587436332767415E-2},{"$f":"IF('Data Sheet'!E30>0, 'Data Sheet'!E31/'Data Sheet'!E30, 0)","v":5.188199389623601E-2},{"$f":"IF('Data Sheet'!F30>0, 'Data Sheet'!F31/'Data Sheet'!F30, 0)","v":0},{"$f":"IF('Data Sheet'!G30>0, 'Data Sheet'!G31/'Data Sheet'!G30, 0)","v":2.0843672456575684E-2},{"$f":"IF('Data Sheet'!H30>0, 'Data Sheet'!H31/'Data Sheet'!H30, 0)","v":2.0157480314960629E-2},{"$f":"IF('Data Sheet'!I30>0, 'Data Sheet'!I31/'Data Sheet'!I30, 0)","v":1.5053128689492325E-2},{"$f":"IF('Data Sheet'!J30>0, 'Data Sheet'!J31/'Data Sheet'!J30, 0)","v":1.1736658719970658E-2},{"$f":"IF('Data Sheet'!K30>0, 'Data Sheet'!K31/'Data Sheet'!K30, 0)","v":6.5100193266198758E-3}]
["OPM",{"$f":"IF(B6>0,B6/B4,0)","v":6.1880707208082426E-2},{"$f":"IF(C6>0,C6/C4,0)","v":6.460391050191476E-2},6.995621061625544E-2,0.11757661148291632,0.13893838760192229,0.17697346508271344,0.18826109803742383,0.17989406263159052,0.1788682295877122,0.19361882044097797,0.18857465379265856]
[]
[]
[null,null,null,null,null,null,"TRENDS:","10 YEARS","7 YEARS","5 YEARS","3 YEARS","RECENT","BEST","WORST"]
[null,null,null,null,null,null,"Sales Growth",{"$f":"IF(B4=0,\"\",POWER($K4/B4,1/9)-1)","v":0.25452758481463023},{"$f":"IF(D4=0,\"\",POWER($K4/D4,1/7)-1)","v":0.35674654785464965},{"$f":"IF(F4=0,\"\",POWER($K4/F4,1/5)-1)","v":0.33738889787061588},{"$f":"IF(H4=0,\"\",POWER($K4/H4, 1/3)-1)","v":0.21874587432400716},{"$f":"IF(ISERROR(MAX(IF(J4=0,\"\",(K4-J4)/J4),IF(K4=0,\"\",(L4-K4)/K4))),\"\",MAX(IF(J4=0,\"\",(K4-J4)/J4),IF(K4=0,\"\",(L4-K4)/K4)))","v":0.281050929668553},{"$f":"MAX(K23:L23)","v":0.281050929668553},{"$f":"MIN(H23:L23)","v":0.21874587432400716}]
[null,null,null,null,null,null,"OPM",{"$f":"IF(SUM(B4:$K$4)=0,\"\",SUMPRODUCT(B19:$K$19,B4:$K$4)/SUM(B4:$K$4))","v":0.16848312792801576},{"$f":"IF(SUM(E4:$K$4)=0,\"\",SUMPRODUCT(E19:$K$19,E4:$K$4)/SUM(E4:$K$4))","v":0.17869541201479672},{"$f":"IF(SUM(G4:$K$4)=0,\"\",SUMPRODUCT(G19:$K$19,G4:$K$4)/SUM(G4:$K$4))","v":0.184724869455378},{"$f":"IF(SUM(I4:$K$4)=0, \"\", SUMPRODUCT(I19:$K$19,I4:$K$4)/SUM(I4:$K$4))","v":0.18539343945350265},{"$f":"L19","v":0.18857465379265856},{"$f":"MAX(K24:L24)","v":0.18857465379265856},{"$f":"MIN(H24:L24)","v":0.16848312792801576}]
[null,null,null,null,null,null,"Price to Earning",{"$f":"IF(ISERROR(AVERAGEIF(B14:$L14,\">0\")),\"\",AVERAGEIF(B14:$L14,\">0\"))","v":10.836810953819809},{"$f":"IF(ISERROR(AVERAGEIF(E14:$L14,\">0\")),\"\",AVERAGEIF(E14:$L14,\">0\"))","v":12.850739843316402},{"$f":"IF(ISERROR(AVERAGEIF(G14:$L14,\">0\")),\"\",AVERAGEIF(G14:$L14,\">0\"))","v":15.225667798353655},{"$f":"IF(ISERROR(AVERAGEIF(I14:$L14,\">0\")),\"\",AVERAGEIF(I14:$L14,\">0\"))","v":18.199420328920237},{"$f":"L14","v":15.655249708598584},{"$f":"MAX(K25:L25)","v":18.199420328920237},{"$f":"MIN(H25:L25)","v":10.836810953819809}]

{"sheet":"Quarters","index":1,"n_rows":14,"n_cols":11,"rows_kept":14,"cut":false,"hidden":true,"merged":[]}
[{"$f":"'Profit & Loss'!A1","v":"BHARAT RASAYAN LTD"},null,null,null,{"$f":"UPDATE","v":""},null,null,null,null,"SCREENER.IN"]
[]
["Narration",{"$f":"'Data Sheet'!B41","v":"2016-12-31"},{"$f":"'Data Sheet'!C41","v":"2017-03-31"},{"$f":"'Data Sheet'!D41","v":"2017-06-30"},{"$f":"'Data Sheet'!E41","v":"2017-09-30"},{"$f":"'Data Sheet'!F41","v":"2017-12-31"},{"$f":"'Data Sheet'!G41","v":"2018-03-31"},{"$f":"'Data Sheet'!H41","v":"2018-06-30"},{"$f":"'Data Sheet'!I41","v":"2018-09-30"},{"$f":"'Data Sheet'!J41","v":"2018-12-31"},{"$f":"'Data Sheet'!K41","v":"2019-03-31"}]
["Sales",{"$f":"'Data Sheet'!B42","v":130.15},{"$f":"'Data Sheet'!C42","v":132.51},{"$f":"'Data Sheet'!D42","v":169.15},{"$f":"'Data Sheet'!E42","v":244.06},{"$f":"'Data Sheet'!F42","v":188.66},{"$f":"'Data Sheet'!G42","v":193.44},{"$f":"'Data Sheet'!H42","v":245.12},{"$f":"'Data Sheet'!I42","v":285.27},{"$f":"'Data Sheet'!J42","v":189.56},{"$f":"'Data Sheet'!K42","v":272.23}]
["Expenses",{"$f":"'Data Sheet'!B43","v":107.56},{"$f":"'Data Sheet'!C43","v":101.01},{"$f":"'Data Sheet'!D43","v":139.41},{"$f":"'Data Sheet'!E43","v":198.74},{"$f":"'Data Sheet'!F43","v":143.77000000000001},{"$f":"'Data Sheet'!G43","v":155.19999999999999},{"$f":"'Data Sheet'!H43","v":204.1},{"$f":"'Data Sheet'!I43","v":226.5},{"$f":"'Data Sheet'!J43","v":150.13},{"$f":"'Data Sheet'!K43","v":224.35}]
["Operating Profit",{"$f":"'Data Sheet'!B50","v":22.59},{"$f":"'Data Sheet'!C50","v":31.5},{"$f":"'Data Sheet'!D50","v":29.74},{"$f":"'Data Sheet'!E50","v":45.32},{"$f":"'Data Sheet'!F50","v":44.89},{"$f":"'Data Sheet'!G50","v":38.24},{"$f":"'Data Sheet'!H50","v":41.02},{"$f":"'Data Sheet'!I50","v":58.77},{"$f":"'Data Sheet'!J50","v":39.43},{"$f":"'Data Sheet'!K50","v":47.88}]
["Other Income",{"$f":"'Data Sheet'!B44","v":2.5},{"$f":"'Data Sheet'!C44","v":-5.12},{"$f":"'Data Sheet'!D44","v":0.68},{"$f":"'Data Sheet'!E44","v":-0.18},{"$f":"'Data Sheet'!F44","v":-2.62},{"$f":"'Data Sheet'!G44","v":6.62},{"$f":"'Data Sheet'!H44","v":1.78},{"$f":"'Data Sheet'!I44","v":0.56000000000000005},{"$f":"'Data Sheet'!J44","v":-0.12},{"$f":"'Data Sheet'!K44","v":-1.47}]
["Depreciation",{"$f":"'Data Sheet'!B45","v":4.0999999999999996},{"$f":"'Data Sheet'!C45","v":4.29},{"$f":"'Data Sheet'!D45","v":3.88},{"$f":"'Data Sheet'!E45","v":4.03},{"$f":"'Data Sheet'!F45","v":4.18},{"$f":"'Data Sheet'!G45","v":4.33},{"$f":"'Data Sheet'!H45","v":4.03},{"$f":"'Data Sheet'!I45","v":4.25},{"$f":"'Data Sheet'!J45","v":4.3499999999999996},{"$f":"'Data Sheet'!K45","v":4.26}]
["Interest",{"$f":"'Data Sheet'!B46","v":3.99},{"$f":"'Data Sheet'!C46","v":2.46},{"$f":"'Data Sheet'!D46","v":2.8},{"$f":"'Data Sheet'!E46","v":2.93},{"$f":"'Data Sheet'!F46","v":2.73},{"$f":"'Data Sheet'!G46","v":2.1800000000000002},{"$f":"'Data Sheet'!H46","v":3.09},{"$f":"'Data Sheet'!I46","v":4.01},{"$f":"'Data Sheet'!J46","v":4.13},{"$f":"'Data Sheet'!K46","v":4.59}]
["Profit before tax",{"$f":"'Data Sheet'!B47","v":17},{"$f":"'Data Sheet'!C47","v":19.63},{"$f":"'Data Sheet'!D47","v":23.74},{"$f":"'Data Sheet'!E47","v":38.18},{"$f":"'Data Sheet'!F47","v":35.36},{"$f":"'Data Sheet'!G47","v":38.35},{"$f":"'Data Sheet'!H47","v":35.68},{"$f":"'Data Sheet'!I47","v":51.07},{"$f":"'Data Sheet'!J47","v":30.83},{"$f":"'Data Sheet'!K47","v":37.56}]
["Tax",{"$f":"'Data Sheet'!B48","v":5.76},{"$f":"'Data Sheet'!C48","v":7.52},{"$f":"'Data Sheet'!D48","v":8.11},{"$f":"'Data Sheet'!E48","v":14.1},{"$f":"'Data Sheet'!F48","v":12.27},{"$f":"'Data Sheet'!G48","v":2.83},{"$f":"'Data Sheet'!H48","v":10.7},{"$f":"'Data Sheet'!I48","v":15.28},{"$f":"'Data Sheet'!J48","v":9.48},{"$f":"'Data Sheet'!K48","v":8.15}]
["Net profit",{"$f":"'Data Sheet'!B49","v":11.24},{"$f":"'Data Sheet'!C49","v":12.11},{"$f":"'Data Sheet'!D49","v":15.63},{"$f":"'Data Sheet'!E49","v":24.08},{"$f":"'Data Sheet'!F49","v":23.09},{"$f":"'Data Sheet'!G49","v":35.520000000000003},{"$f":"'Data Sheet'!H49","v":24.98},{"$f":"'Data Sheet'!I49","v":35.79},{"$f":"'Data Sheet'!J49","v":21.35},{"$f":"'Data Sheet'!K49","v":29.41}]
[]
["OPM",{"$f":"IF(B4>0,B6/B4,\"\")","v":0.17356895889358431},{"$f":"IF(C4>0,C6/C4,\"\")","v":0.23771790808240889},0.17582027785988766,0.18569204294026059,0.23794127000954099,0.19768403639371382,0.16734660574412533,0.20601535387527609,0.20800801856931841,0.1758806891231679]

{"sheet":"Balance Sheet","index":2,"n_rows":37,"n_cols":12,"rows_kept":37,"cut":false,"hidden":true,"merged":[]}
[{"$f":"'Profit & Loss'!A1","v":"BHARAT RASAYAN LTD"},null,null,null,{"$f":"UPDATE","v":""},null,null,null,null,"SCREENER.IN"]
[]
["Narration",{"$f":"'Data Sheet'!B56","v":"2009-03-31"},{"$f":"'Data Sheet'!C56","v":"2010-03-31"},{"$f":"'Data Sheet'!D56","v":"2011-03-31"},{"$f":"'Data Sheet'!E56","v":"2012-03-31"},{"$f":"'Data Sheet'!F56","v":"2013-03-31"},{"$f":"'Data Sheet'!G56","v":"2014-03-31"},{"$f":"'Data Sheet'!H56","v":"2015-03-31"},{"$f":"'Data Sheet'!I56","v":"2016-03-31"},{"$f":"'Data Sheet'!J56","v":"2017-03-31"},{"$f":"'Data Sheet'!K56","v":"2018-03-31"}]
["Equity Share Capital",{"$f":"'Data Sheet'!B57","v":4.25},{"$f":"'Data Sheet'!C57","v":4.25},{"$f":"'Data Sheet'!D57","v":4.25},{"$f":"'Data Sheet'!E57","v":4.25},{"$f":"'Data Sheet'!F57","v":4.25},{"$f":"'Data Sheet'!G57","v":4.25},{"$f":"'Data Sheet'!H57","v":4.25},{"$f":"'Data Sheet'!I57","v":4.25},{"$f":"'Data Sheet'!J57","v":4.25},{"$f":"'Data Sheet'!K57","v":4.25}]
["Reserves",{"$f":"'Data Sheet'!B58","v":33.82},{"$f":"'Data Sheet'!C58","v":38.74},{"$f":"'Data Sheet'!D58","v":39.49},{"$f":"'Data Sheet'!E58","v":48.68},{"$f":"'Data Sheet'!F58","v":58.28},{"$f":"'Data Sheet'!G58","v":77.930000000000007},{"$f":"'Data Sheet'!H58","v":108.89},{"$f":"'Data Sheet'!I58","v":142.15},{"$f":"'Data Sheet'!J58","v":196.46},{"$f":"'Data Sheet'!K58","v":294}]
["Borrowings",{"$f":"'Data Sheet'!B59","v":12.72},{"$f":"'Data Sheet'!C59","v":3.79},{"$f":"'Data Sheet'!D59","v":8.4499999999999993},{"$f":"'Data Sheet'!E59","v":39.1},{"$f":"'Data Sheet'!F59","v":131.15},{"$f":"'Data Sheet'!G59","v":143.22999999999999},{"$f":"'Data Sheet'!H59","v":140.16},{"$f":"'Data Sheet'!I59","v":110.77},{"$f":"'Data Sheet'!J59","v":114.71},{"$f":"'Data Sheet'!K59","v":128.34}]
["Other Liabilities",{"$f":"'Data Sheet'!B60","v":13.34},{"$f":"'Data Sheet'!C60","v":13.54},{"$f":"'Data Sheet'!D60","v":12.72},{"$f":"'Data Sheet'!E60","v":33.880000000000003},{"$f":"'Data Sheet'!F60","v":52.58},{"$f":"'Data Sheet'!G60","v":81.91},{"$f":"'Data Sheet'!H60","v":82.1},{"$f":"'Data Sheet'!I60","v":68.599999999999994},{"$f":"'Data Sheet'!J60","v":54.64},{"$f":"'Data Sheet'!K60","v":77.489999999999995}]
["Total",{"$f":"'Data Sheet'!B61","v":64.13},{"$f":"'Data Sheet'!C61","v":60.32},{"$f":"'Data Sheet'!D61","v":64.91},{"$f":"'Data Sheet'!E61","v":125.91},{"$f":"'Data Sheet'!F61","v":246.26},{"$f":"'Data Sheet'!G61","v":307.32},{"$f":"'Data Sheet'!H61","v":335.4},{"$f":"'Data Sheet'!I61","v":325.77},{"$f":"'Data Sheet'!J61","v":370.06},{"$f":"'Data Sheet'!K61","v":504.08}]
[]
["Net Block",{"$f":"'Data Sheet'!B62","v":5.42},{"$f":"'Data Sheet'!C62","v":5.59},{"$f":"'Data Sheet'!D62","v":19.95},{"$f":"'Data Sheet'!E62","v":16.239999999999998},{"$f":"'Data Sheet'!F62","v":135.05000000000001},{"$f":"'Data Sheet'!G62","v":142.26},{"$f":"'Data Sheet'!H62","v":136.62},{"$f":"'Data Sheet'!I62","v":135.72},{"$f":"'Data Sheet'!J62","v":131.03},{"$f":"'Data Sheet'!K62","v":147.72}]
["Capital Work in Progress",{"$f":"'Data Sheet'!B63","v":0},{"$f":"'Data Sheet'!C63","v":0},{"$f":"'Data Sheet'!D63","v":3.28},{"$f":"'Data Sheet'!E63","v":48.27},{"$f":"'Data Sheet'!F63","v":0},{"$f":"'Data Sheet'!G63","v":0.56999999999999995},{"$f":"'Data Sheet'!H63","v":1.67},{"$f":"'Data Sheet'!I63","v":0.54},{"$f":"'Data Sheet'!J63","v":1.21},{"$f":"'Data Sheet'!K63","v":7.14}]
["Investments",{"$f":"'Data Sheet'!B64","v":4.38},{"$f":"'Data Sheet'!C64","v":11.42},{"$f":"'Data Sheet'!D64","v":1.1100000000000001},{"$f":"'Data Sheet'!E64","v":0.99},{"$f":"'Data Sheet'!F64","v":0.28000000000000003},{"$f":"'Data Sheet'!G64","v":0.26},{"$f":"'Data Sheet'!H64","v":29.79},{"$f":"'Data Sheet'!I64","v":20.14},{"$f":"'Data Sheet'!J64","v":0.09},{"$f":"'Data Sheet'!K64","v":0.09}]
["Other Assets",{"$f":"'Data Sheet'!B65","v":54.33},{"$f":"'Data Sheet'!C65","v":43.31},{"$f":"'Data Sheet'!D65","v":40.57},{"$f":"'Data Sheet'!E65","v":60.41},{"$f":"'Data Sheet'!F65","v":110.93},{"$f":"'Data Sheet'!G65","v":164.23},{"$f":"'Data Sheet'!H65","v":167.32},{"$f":"'Data Sheet'!I65","v":169.37},{"$f":"'Data Sheet'!J65","v":237.73},{"$f":"'Data Sheet'!K65","v":349.13}]
["Total",{"$f":"'Data Sheet'!B66","v":64.13},{"$f":"'Data Sheet'!C66","v":60.32},{"$f":"'Data Sheet'!D66","v":64.91},{"$f":"'Data Sheet'!E66","v":125.91},{"$f":"'Data Sheet'!F66","v":246.26},{"$f":"'Data Sheet'!G66","v":307.32},{"$f":"'Data Sheet'!H66","v":335.4},{"$f":"'Data Sheet'!I66","v":325.77},{"$f":"'Data Sheet'!J66","v":370.06},{"$f":"'Data Sheet'!K66","v":504.08}]
[]
["Working Capital",{"$f":"B13-B7","v":40.989999999999995},{"$f":"C13-C7","v":29.770000000000003},27.85,26.529999999999994,58.350000000000009,82.32,85.22,100.77000000000001,183.08999999999997,271.64]
["Debtors",{"$f":"'Data Sheet'!B67","v":22.26},{"$f":"'Data Sheet'!C67","v":16.920000000000002},{"$f":"'Data Sheet'!D67","v":15.93},{"$f":"'Data Sheet'!E67","v":30.04},{"$f":"'Data Sheet'!F67","v":45.02},{"$f":"'Data Sheet'!G67","v":60.41},{"$f":"'Data Sheet'!H67","v":79.53},{"$f":"'Data Sheet'!I67","v":88.17},{"$f":"'Data Sheet'!J67","v":120.15},{"$f":"'Data Sheet'!K67","v":221.61}]
["Inventory",{"$f":"'Data Sheet'!B68","v":11.24},{"$f":"'Data Sheet'!C68","v":13.58},{"$f":"'Data Sheet'!D68","v":11.82},{"$f":"'Data Sheet'!E68","v":16.71},{"$f":"'Data Sheet'!F68","v":37.26},{"$f":"'Data Sheet'!G68","v":67.430000000000007},{"$f":"'Data Sheet'!H68","v":57.39},{"$f":"'Data Sheet'!I68","v":56.75},{"$f":"'Data Sheet'!J68","v":83.86},{"$f":"'Data Sheet'!K68","v":94.17}]
[]
["Inventory Turnover",{"$f":"IF('Balance Sheet'!B18>0,'Profit & Loss'!B4/'Balance Sheet'!B18,0)","v":9.1583629893238427},{"$f":"IF('Balance Sheet'!C18>0,'Profit & Loss'!C4/'Balance Sheet'!C18,0)","v":7.3063328424153164},{"$f":"IF('Balance Sheet'!D18>0,'Profit & Loss'!D4/'Balance Sheet'!D18,0)","v":7.9213197969543145},{"$f":"IF('Balance Sheet'!E18>0,'Profit & Loss'!E4/'Balance Sheet'!E18,0)","v":8.4949132256134039},{"$f":"IF('Balance Sheet'!F18>0,'Profit & Loss'!F4/'Balance Sheet'!F18,0)","v":4.9702093397745575},{"$f":"IF('Balance Sheet'!G18>0,'Profit & Loss'!G4/'Balance Sheet'!G18,0)","v":5.3430223935933547},{"$f":"IF('Balance Sheet'!H18>0,'Profit & Loss'!H4/'Balance Sheet'!H18,0)","v":7.6265899982575363},{"$f":"IF('Balance Sheet'!I18>0,'Profit & Loss'!I4/'Balance Sheet'!I18,0)","v":7.9508370044052858},{"$f":"IF('Balance Sheet'!J18>0,'Profit & Loss'!J4/'Balance Sheet'!J18,0)","v":7.3753875506797044},{"$f":"IF('Balance Sheet'!K18>0,'Profit & Loss'!K4/'Balance Sheet'!K18,0)","v":8.4138260592545393}]
["Inventory Days",{"$f":"IF('Profit & Loss'!B4>0,'Balance Sheet'!B18/('Profit & Loss'!B4/365),0)","v":39.854284048960558},{"$f":"IF('Profit & Loss'!C4>0,'Balance Sheet'!C18/('Profit & Loss'!C4/365),0)","v":49.956661963313842},{"$f":"IF('Profit & Loss'!D4>0,'Balance Sheet'!D18/('Profit & Loss'!D4/365),0)","v":46.078180070490234},{"$f":"IF('Profit & Loss'!E4>0,'Balance Sheet'!E18/('Profit & Loss'!E4/365),0)","v":42.966889749911942},{"$f":"IF('Profit & Loss'!F4>0,'Balance Sheet'!F18/('Profit & Loss'!F4/365),0)","v":73.437550623683791},{"$f":"IF('Profit & Loss'!G4>0,'Balance Sheet'!G18/('Profit & Loss'!G4/365),0)","v":68.313395137115592},{"$f":"IF('Profit & Loss'!H4>0,'Balance Sheet'!H18/('Profit & Loss'!H4/365),0)","v":47.858872718133846},{"$f":"IF('Profit & Loss'!I4>0,'Balance Sheet'!I18/('Profit & Loss'!I4/365),0)","v":45.907116420292105},{"$f":"IF('Profit & Loss'!J4>0,'Balance Sheet'!J18/('Profit & Loss'!J4/365),0)","v":49.48892481810833},{"$f":"IF('Profit & Loss'!K4>0,'Balance Sheet'!K18/('Profit & Loss'!K4/365),0)","v":43.380977622960131}]
["Debtor Days",{"$f":"IF('Profit & Loss'!B4>0,'Balance Sheet'!B17/('Profit & Loss'!B4/365),0)","v":78.928502040023318},{"$f":"IF('Profit & Loss'!C4>0,'Balance Sheet'!C17/('Profit & Loss'!C4/365),0)","v":62.243499294497077},{"$f":"IF('Profit & Loss'!D4>0,'Balance Sheet'!D17/('Profit & Loss'!D4/365),0)","v":62.100288369112469},{"$f":"IF('Profit & Loss'!E4>0,'Balance Sheet'!E17/('Profit & Loss'!E4/365),0)","v":77.242691088411405},{"$f":"IF('Profit & Loss'!F4>0,'Balance Sheet'!F17/('Profit & Loss'!F4/365),0)","v":88.732112965062925},{"$f":"IF('Profit & Loss'!G4>0,'Balance Sheet'!G17/('Profit & Loss'!G4/365),0)","v":61.201426668146993},{"$f":"IF('Profit & Loss'!H4>0,'Balance Sheet'!H17/('Profit & Loss'!H4/365),0)","v":66.321940185976374},{"$f":"IF('Profit & Loss'!I4>0,'Balance Sheet'!I17/('Profit & Loss'!I4/365),0)","v":71.323884665676729},{"$f":"IF('Profit & Loss'!J4>0,'Balance Sheet'!J17/('Profit & Loss'!J4/365),0)","v":70.905012126111558},{"$f":"IF('Profit & Loss'!K4>0,'Balance Sheet'!K17/('Profit & Loss'!K4/365),0)","v":102.08833440611866}]
["Creditor Days"]
["Cash Conversion Cycle"]
[]
["Return on Equity",{"$f":"IF(SUM('Balance Sheet'!B4:B5)>0,'Profit & Loss'!B12/SUM('Balance Sheet'!B4:B5),\"\")","v":0.13580246913580246},{"$f":"IF(SUM('Balance Sheet'!C4:C5)>0,'Profit & Loss'!C12/SUM('Balance Sheet'!C4:C5),\"\")","v":0.13514770876948126},{"$f":"IF(SUM('Balance Sheet'!D4:D5)>0,'Profit & Loss'!D12/SUM('Balance Sheet'!D4:D5),\"\")","v":0.13465935070873342},{"$f":"IF(SUM('Balance Sheet'!E4:E5)>0,'Profit & Loss'!E12/SUM('Balance Sheet'!E4:E5),\"\")","v":0.18571698469676931},{"$f":"IF(SUM('Balance Sheet'!F4:F5)>0,'Profit & Loss'!F12/SUM('Balance Sheet'!F4:F5),\"\")","v":0.1533663841356149},{"$f":"IF(SUM('Balance Sheet'!G4:G5)>0,'Profit & Loss'!G12/SUM('Balance Sheet'!G4:G5),\"\")","v":0.24519347773180819},{"$f":"IF(SUM('Balance Sheet'!H4:H5)>0,'Profit & Loss'!H12/SUM('Balance Sheet'!H4:H5),\"\")","v":0.28062577337811562},{"$f":"IF(SUM('Balance Sheet'!I4:I5)>0,'Profit & Loss'!I12/SUM('Balance Sheet'!I4:I5),\"\")","v":0.23142076502732242},{"$f":"IF(SUM('Balance Sheet'!J4:J5)>0,'Profit & Loss'!J12/SUM('Balance Sheet'!J4:J5),\"\")","v":0.27168551641672062},{"$f":"IF(SUM('Balance Sheet'!K4:K5)>0,'Profit & Loss'!K12/SUM('Balance Sheet'!K4:K5),\"\")","v":0.32962279966471081}]
["Return on Capital Emp",{"$f":"IF(('Balance Sheet'!B10+'Balance Sheet'!B16)>0,('Profit & Loss'!B6-'Profit & Loss'!B8-'Profit & Loss'!B11)/('Balance Sheet'!B10+'Balance Sheet'!B16),\"\")","v":3.9646627881922102E-2},{"$f":"IF(('Balance Sheet'!C10+'Balance Sheet'!C16)>0,('Profit & Loss'!C6-'Profit & Loss'!C8-'Profit & Loss'!C11)/('Balance Sheet'!C10+'Balance Sheet'!C16),\"\")","v":7.4943438914026661E-2},{"$f":"IF(('Balance Sheet'!D10+'Balance Sheet'!D16)>0,('Profit & Loss'!D6-'Profit & Loss'!D8-'Profit & Loss'!D11)/('Balance Sheet'!D10+'Balance Sheet'!D16),\"\")","v":5.4393305439330478E-2},{"$f":"IF(('Balance Sheet'!E10+'Balance Sheet'!E16)>0,('Profit & Loss'!E6-'Profit & Loss'!E8-'Profit & Loss'!E11)/('Balance Sheet'!E10+'Balance Sheet'!E16),\"\")","v":0.26139817629179257},{"$f":"IF(('Balance Sheet'!F10+'Balance Sheet'!F16)>0,('Profit & Loss'!F6-'Profit & Loss'!F8-'Profit & Loss'!F11)/('Balance Sheet'!F10+'Balance Sheet'!F16),\"\")","v":7.4043433298862399E-2},{"$f":"IF(('Balance Sheet'!G10+'Balance Sheet'!G16)>0,('Profit & Loss'!G6-'Profit & Loss'!G8-'Profit & Loss'!G11)/('Balance Sheet'!G10+'Balance Sheet'!G16),\"\")","v":0.16038828034553387},{"$f":"IF(('Balance Sheet'!H10+'Balance Sheet'!H16)>0,('Profit & Loss'!H6-'Profit & Loss'!H8-'Profit & Loss'!H11)/('Balance Sheet'!H10+'Balance Sheet'!H16),\"\")","v":0.21799495131626409},{"$f":"IF(('Balance Sheet'!I10+'Balance Sheet'!I16)>0,('Profit & Loss'!I6-'Profit & Loss'!I8-'Profit & Loss'!I11)/('Balance Sheet'!I10+'Balance Sheet'!I16),\"\")","v":0.19645650978899723},{"$f":"IF(('Balance Sheet'!J10+'Balance Sheet'!J16)>0,('Profit & Loss'!J6-'Profit & Loss'!J8-'Profit & Loss'!J11)/('Balance Sheet'!J10+'Balance Sheet'!J16),\"\")","v":0.20632242455112693},{"$f":"IF(('Balance Sheet'!K10+'Balance Sheet'!K16)>0,('Profit & Loss'!K6-'Profit & Loss'!K8-'Profit & Loss'!K11)/('Balance Sheet'!K10+'Balance Sheet'!K16),\"\")","v":0.23769553605494101}]
[]
[]
[]
["Common Size Balance Sheet",{"$f":"B3","v":"2009-03-31"},{"$f":"C3","v":"2010-03-31"},"2011-03-31","2012-03-31","2013-03-31","2014-03-31","2015-03-31","2016-03-31","2017-03-31","2018-03-31","Check back how Assets are being put to use"]
["Net Block/Total Assets",{"$f":"B10/B$8","v":8.4515827225947304E-2},{"$f":"C10/C$8","v":9.2672413793103439E-2},0.30734863657371747,0.1289810181875943,0.54840412572078301,0.46290511518937916,0.40733452593917713,0.41661294778524727,0.35407771712695241,0.2930487224250119]
["Working Capital/Total Assets",{"$f":"B16/B$8","v":0.63917043505379689},{"$f":"C16/C$8","v":0.49353448275862072},0.42905561546757054,0.21070605988404412,0.23694469260131573,0.26786411557985162,0.25408467501490761,0.30932866746477583,0.49475760687456083,0.538882717029043]
["Debtors/Total Assets",{"$f":"B17/B$8","v":0.34710743801652899},{"$f":"C17/C$8","v":0.2805039787798409},0.24541673085811125,0.23858311492335796,0.18281491106960127,0.19657035012364962,0.23711985688729878,0.27065107284280321,0.32467707939253093,0.43963259800031745]
["Inventory/Total Assets",{"$f":"B18/B$8","v":0.17526898487447373},{"$f":"C18/C$8","v":0.22513262599469497},0.18209828993991684,0.1327138432213486,0.15130350036546739,0.21941298971755827,0.17110912343470483,0.17420265831721768,0.22661190077284765,0.18681558482780511]
[]
["Borrowings/Total Assets",{"$f":"B6/B$8","v":0.19834710743801656},{"$f":"C6/C$8","v":6.2831564986737407E-2},0.13018024957633645,0.31053927408466364,0.53256720539267444,0.46606143433554598,0.41788908765652955,0.34002517113300795,0.30997676052532019,0.25460244405649896]

{"sheet":"Cash Flow","index":3,"n_rows":7,"n_cols":11,"rows_kept":7,"cut":false,"hidden":true,"merged":[]}
[{"$f":"'Balance Sheet'!A1","v":"BHARAT RASAYAN LTD"},null,null,null,{"$f":"UPDATE","v":""},null,null,null,null,"SCREENER.IN"]
[]
["Narration",{"$f":"'Data Sheet'!B81","v":"2009-03-31"},{"$f":"'Data Sheet'!C81","v":"2010-03-31"},{"$f":"'Data Sheet'!D81","v":"2011-03-31"},{"$f":"'Data Sheet'!E81","v":"2012-03-31"},{"$f":"'Data Sheet'!F81","v":"2013-03-31"},{"$f":"'Data Sheet'!G81","v":"2014-03-31"},{"$f":"'Data Sheet'!H81","v":"2015-03-31"},{"$f":"'Data Sheet'!I81","v":"2016-03-31"},{"$f":"'Data Sheet'!J81","v":"2017-03-31"},{"$f":"'Data Sheet'!K81","v":"2018-03-31"}]
["Cash from Operating Activity",{"$f":"'Data Sheet'!B82","v":-2.23},{"$f":"'Data Sheet'!C82","v":18.760000000000002},{"$f":"'Data Sheet'!D82","v":10.07},{"$f":"'Data Sheet'!E82","v":12.54},{"$f":"'Data Sheet'!F82","v":-7.55},{"$f":"'Data Sheet'!G82","v":28.52},{"$f":"'Data Sheet'!H82","v":59.71},{"$f":"'Data Sheet'!I82","v":46.73},{"$f":"'Data Sheet'!J82","v":15.78},{"$f":"'Data Sheet'!K82","v":28.81}]
["Cash from Investing Activity",{"$f":"'Data Sheet'!B83","v":-3.99},{"$f":"'Data Sheet'!C83","v":-8.0500000000000007},{"$f":"'Data Sheet'!D83","v":-6.93},{"$f":"'Data Sheet'!E83","v":-41.81},{"$f":"'Data Sheet'!F83","v":-76.69},{"$f":"'Data Sheet'!G83","v":-25.36},{"$f":"'Data Sheet'!H83","v":-40.97},{"$f":"'Data Sheet'!I83","v":-4.99},{"$f":"'Data Sheet'!J83","v":7.77},{"$f":"'Data Sheet'!K83","v":-30.85}]
["Cash from Financing Activity",{"$f":"'Data Sheet'!B84","v":4.8600000000000003},{"$f":"'Data Sheet'!C84","v":-9.6199999999999992},{"$f":"'Data Sheet'!D84","v":-5.23},{"$f":"'Data Sheet'!E84","v":29.79},{"$f":"'Data Sheet'!F84","v":87.01},{"$f":"'Data Sheet'!G84","v":-2.65},{"$f":"'Data Sheet'!H84","v":-18.98},{"$f":"'Data Sheet'!I84","v":-42.62},{"$f":"'Data Sheet'!J84","v":-23.9},{"$f":"'Data Sheet'!K84","v":2.23}]
["Net Cash Flow",{"$f":"'Data Sheet'!B85","v":-1.36},{"$f":"'Data Sheet'!C85","v":1.0900000000000001},{"$f":"'Data Sheet'!D85","v":-2.09},{"$f":"'Data Sheet'!E85","v":0.52},{"$f":"'Data Sheet'!F85","v":2.77},{"$f":"'Data Sheet'!G85","v":0.51},{"$f":"'Data Sheet'!H85","v":-0.25},{"$f":"'Data Sheet'!I85","v":-0.88},{"$f":"'Data Sheet'!J85","v":-0.34},{"$f":"'Data Sheet'!K85","v":0.18}]

{"sheet":"Customization","index":4,"n_rows":65,"n_cols":14,"rows_kept":65,"cut":false,"hidden":false,"merged":[[50,0,50,10],[3,5,3,10],[3,12,3,13],[9,0,9,9],[33,0,33,10],[42,0,42,10]]}
[{"$f":"'Data Sheet'!B1","v":"BHARAT RASAYAN LTD"}]
[null,null,null,null,null,null,null,null,null,null,null,null," "]
[null,null,null,null,null,null,null,null,null,null,null,null," "]
[null,"DELTA NETWORTH","DELTA MKTCAP","IMPACT*",null,"HISTORICAL VALUATIONS",null,null,null,null,null,null,"PRE-TAX BOND"]
["10 YR",{"$f":"KeyMetrics!K12-KeyMetrics!B12","v":260.18},{"$f":"KeyMetrics!K27-KeyMetrics!B27","v":2110.0829680658894},{"$f":"C5/B5","v":8.1100890462982917},null,null,"P/E","P/B","EV/EBITDA","P/SALES","YIELD",null,"LongTerm Bond",0.09]
["7 YR",{"$f":"KeyMetrics!K12-KeyMetrics!E12","v":245.32},{"$f":"KeyMetrics!K27-KeyMetrics!E27","v":2073.6970773613893},{"$f":"C6/B6","v":8.4530290125606946},null,"MIN",{"$f":"MIN(KeyMetrics!B34:K34)","v":3.8906938315411987},{"$f":"MIN(KeyMetrics!B35:K35)","v":0.52836582897473072},{"$f":"MIN(KeyMetrics!B38:K38)","v":3.0356018147263057},{"$f":"MIN(KeyMetrics!B37:K37)","v":0.19540399367658828},{"$f":"MAX(KeyMetrics!B39:K39)","v":2.1890349077453668E-2},null,"LTB Quote",{"$f":"('Profit & Loss'!$L$10/'Data Sheet'!$B$61)/N5","v":26.879428937747978}]
["5 YR",{"$f":"KeyMetrics!K12-KeyMetrics!G12","v":216.07},{"$f":"KeyMetrics!K27-KeyMetrics!G27","v":1992.3137457808696},{"$f":"C7/B7","v":9.2206865635251063},null,"MAX",{"$f":"MAX(KeyMetrics!B34:K34)","v":23.330004110146266},{"$f":"MAX(KeyMetrics!B35:K35)","v":7.142323068482674},{"$f":"MAX(KeyMetrics!B38:K38)","v":13.807657957079579},{"$f":"MAX(KeyMetrics!B37:K37)","v":2.6885235383930399},{"$f":"MIN(KeyMetrics!B39:K39)","v":0},null,"Equity Quoting @",{"$f":"('Profit & Loss'!$L$6/'Data Sheet'!$B$6)/'Data Sheet'!$B$8","v":0.10715737988465261}]
["3 YR",{"$f":"KeyMetrics!K12-KeyMetrics!I12","v":151.85},{"$f":"KeyMetrics!K27-KeyMetrics!I27","v":1718.7504327091415},{"$f":"C8/B8","v":11.318738443919273},null,"TRAILING",{"$f":"'Data Sheet'!B8/'Profit & Loss'!L13","v":15.655249708598584},{"$f":"KeyMetrics!L27/KeyMetrics!K12","v":5.8542497904442579},{"$f":"KeyMetrics!K38","v":13.807657957079579},{"$f":"KeyMetrics!L27/'Data Sheet'!K17","v":2.2036651395251976},{"$f":"'Data Sheet'!K31/KeyMetrics!L27","v":3.6654582109127567E-4}]
["1 YR",{"$f":"KeyMetrics!K12-KeyMetrics!J12","v":97.539999999999992},{"$f":"KeyMetrics!K27-KeyMetrics!J27","v":858.01273104868164},{"$f":"C9/B9","v":8.7965217454242541},null,null,null,null,null,null,null,null," "]
["* IMPACT – Every Rupee retained added xx.yy in incremental market value"]
[]
[{"$f":"A1","v":"BHARAT RASAYAN LTD"},"SALES","GROSS PROFIT","EBIT","PAT","DIVIDEND","EPA**","MKTCAP","CFO**","FCF**","NETWORTH","TOTAL RETURNS"]
["10 YR CAGR",{"$f":"POWER('Data Sheet'!$K17/'Data Sheet'!$B17, 1/9)-1","v":0.25452758481463023},{"$f":"POWER(KeyMetrics!$K4/KeyMetrics!$B4, 1/9)-1","v":0.28385447214129877},{"$f":"POWER(KeyMetrics!$K6/KeyMetrics!$B6, 1/9)-1","v":0.35395055358783312},{"$f":"POWER(KeyMetrics!$K9/KeyMetrics!$B9, 1/9)-1","v":0.38714869296180332},{"$f":"POWER(KeyMetrics!$K10/KeyMetrics!$B10, 1/9)-1","v":4.791397344233328E-2},{"$f":"POWER(KeyMetrics!$K25/KeyMetrics!$B25, 1/9)-1","v":1.0404118989979438},{"$f":"POWER(KeyMetrics!$K27/KeyMetrics!$B27, 1/9)-1","v":0.67876207423552914},{"$f":"POWER(KeyMetrics!$K18/KeyMetrics!$B18, 1/9)-1","v":-2.3288346156571853},{"$f":"POWER(KeyMetrics!$K20/KeyMetrics!$C20, 1/8)-1","v":{"$error":"#NUM!"}},{"$f":"POWER(KeyMetrics!$K12/KeyMetrics!$B12, 1/9)-1","v":0.25699359268378075},{"$f":"POWER(KeyMetrics!$K28/KeyMetrics!$B28, 1/9)-1","v":0.67496776646073897}]
["5 YR CAGR",{"$f":"POWER('Data Sheet'!$K17/'Data Sheet'!$G17, 1/4)-1","v":0.21777340841401971},{"$f":"POWER(KeyMetrics!$K4/KeyMetrics!$G4, 1/4)-1","v":0.27040568350740113},{"$f":"POWER(KeyMetrics!$K6/KeyMetrics!$G6, 1/4)-1","v":0.33201085407137199},{"$f":"POWER(KeyMetrics!$K9/KeyMetrics!$G9, 1/4)-1","v":0.48621165037534553},{"$f":"POWER(KeyMetrics!$K10/KeyMetrics!$G10, 1/4)-1","v":0.11104761360471649},{"$f":"POWER(KeyMetrics!$K25/KeyMetrics!$G25, 1/4)-1","v":0.89925609473582657},{"$f":"POWER(KeyMetrics!$K27/KeyMetrics!$G27, 1/4)-1","v":0.98256041795323479},{"$f":"POWER(KeyMetrics!$K18/KeyMetrics!$G18, 1/4)-1","v":2.5324396093113766E-3},{"$f":"POWER(KeyMetrics!$K20/KeyMetrics!$G20, 1/4)-1","v":{"$error":"#NUM!"}},{"$f":"POWER(KeyMetrics!$K12/KeyMetrics!$G12, 1/4)-1","v":0.38023672509355699},{"$f":"POWER(KeyMetrics!$K28/KeyMetrics!$G28, 1/4)-1","v":0.98120232881025315}]
["3 YR CAGR",{"$f":"POWER('Data Sheet'!$K17/'Data Sheet'!$I17, 1/2)-1","v":0.32514588374932973},{"$f":"POWER(KeyMetrics!$K4/KeyMetrics!$I4, 1/2)-1","v":0.31210042639005997},{"$f":"POWER(KeyMetrics!$K6/KeyMetrics!$I6, 1/2)-1","v":0.50508397698526375},{"$f":"POWER(KeyMetrics!$K9/KeyMetrics!$I9, 1/2)-1","v":0.70344120075780636},{"$f":"POWER(KeyMetrics!$K10/KeyMetrics!$I10, 1/2)-1","v":0.12022406722240775},{"$f":"POWER(KeyMetrics!$K25/KeyMetrics!$I25, 1/2)-1","v":0.97654529439319115},{"$f":"POWER(KeyMetrics!$K27/KeyMetrics!$I27, 1/2)-1","v":1.2753740382637981},{"$f":"POWER(KeyMetrics!$K18/KeyMetrics!$I18, 1/2)-1","v":-0.21481184640215323},{"$f":"POWER(KeyMetrics!$K20/KeyMetrics!$I20, 1/2)-1","v":{"$error":"#NUM!"}},{"$f":"POWER(KeyMetrics!$K12/KeyMetrics!$I12, 1/2)-1","v":0.42731453294509825},{"$f":"POWER(KeyMetrics!$K28/KeyMetrics!$I28, 1/2)-1","v":1.27430672581891}]
["1 YR GROWTH",{"$f":"('Data Sheet'!$K17-'Data Sheet'!$J17)/'Data Sheet'!$J17","v":0.281050929668553},{"$f":"(KeyMetrics!$K4-KeyMetrics!$J4)/KeyMetrics!$J4","v":0.40207146556188489},{"$f":"(KeyMetrics!$K6-KeyMetrics!$J6)/KeyMetrics!$J6","v":0.5231918646881808},{"$f":"(KeyMetrics!$K9-KeyMetrics!$J9)/KeyMetrics!$J9","v":0.80286081056299285},{"$f":"(KeyMetrics!$K10-KeyMetrics!$J10)/KeyMetrics!$J10","v":0},{"$f":"(KeyMetrics!$K25-KeyMetrics!$J25)/KeyMetrics!$J25","v":1.2286740936750791},{"$f":"(KeyMetrics!$K27-KeyMetrics!$J27)/KeyMetrics!$J27","v":0.67444015401292812},{"$f":"(KeyMetrics!$K18-KeyMetrics!$J18)/KeyMetrics!$J18","v":0.82572877059569072},{"$f":"(KeyMetrics!$K20-KeyMetrics!$J20)/KeyMetrics!$J20","v":-4.0356083086053438},{"$f":"(KeyMetrics!$K12-KeyMetrics!$J12)/KeyMetrics!$J12","v":0.48597478949728456},{"$f":"(KeyMetrics!$K28-KeyMetrics!$J28)/KeyMetrics!$J28","v":0.67410103303677293}]
["**modify (if, then) for negative values"]
[{"$f":"A1","v":"BHARAT RASAYAN LTD"},{"$f":"'Data Sheet'!B16","v":"2009-03-31"},{"$f":"'Data Sheet'!C16","v":"2010-03-31"},{"$f":"'Data Sheet'!D16","v":"2011-03-31"},{"$f":"'Data Sheet'!E16","v":"2012-03-31"},{"$f":"'Data Sheet'!F16","v":"2013-03-31"},{"$f":"'Data Sheet'!G16","v":"2014-03-31"},{"$f":"'Data Sheet'!H16","v":"2015-03-31"},{"$f":"'Data Sheet'!I16","v":"2016-03-31"},{"$f":"'Data Sheet'!J16","v":"2017-03-31"},{"$f":"'Data Sheet'!K16","v":"2018-03-31"},null,"    "]
["Total Assets/Networth= Financial Leverage",{"$f":"KeyMetrics!B16/KeyMetrics!B12","v":1.6845285001313368},{"$f":"KeyMetrics!C16/KeyMetrics!C12","v":1.4031170039544079},{"$f":"KeyMetrics!D16/KeyMetrics!D12","v":1.4839963420210331},{"$f":"KeyMetrics!E16/KeyMetrics!E12","v":2.3788021915737767},{"$f":"KeyMetrics!F16/KeyMetrics!F12","v":3.9382696305773228},{"$f":"KeyMetrics!G16/KeyMetrics!G12","v":3.7395960087612554},{"$f":"KeyMetrics!H16/KeyMetrics!H12","v":2.9644687997171641},{"$f":"KeyMetrics!I16/KeyMetrics!I12","v":2.2252049180327869},{"$f":"KeyMetrics!J16/KeyMetrics!J12","v":1.8437546709182402},{"$f":"KeyMetrics!K16/KeyMetrics!K12","v":1.6901257334450963}," "]
["Long term debt/Earning",{"$f":"'Data Sheet'!B59/'Data Sheet'!B30","v":2.4603481624758223},{"$f":"'Data Sheet'!C59/'Data Sheet'!C30","v":0.65232358003442348},{"$f":"'Data Sheet'!D59/'Data Sheet'!D30","v":1.4346349745331068},{"$f":"'Data Sheet'!E59/'Data Sheet'!E30","v":3.9776195320447609},{"$f":"'Data Sheet'!F59/'Data Sheet'!F30","v":13.67570385818561},{"$f":"'Data Sheet'!G59/'Data Sheet'!G30","v":7.1081885856079401},{"$f":"'Data Sheet'!H59/'Data Sheet'!H30","v":4.4144881889763781},{"$f":"'Data Sheet'!I59/'Data Sheet'!I30","v":3.2694805194805192},{"$f":"'Data Sheet'!J59/'Data Sheet'!J30","v":2.1036126902622407},{"$f":"'Data Sheet'!K59/'Data Sheet'!K30","v":1.3054623130912419}]
["Current liablility/Earning",{"$f":"'Data Sheet'!B60/'Data Sheet'!B30","v":2.5802707930367506},{"$f":"'Data Sheet'!C60/'Data Sheet'!C30","v":2.3304647160068845},{"$f":"'Data Sheet'!D60/'Data Sheet'!D30","v":2.1595925297113756},{"$f":"'Data Sheet'!E60/'Data Sheet'!E30","v":3.4465920651068163},{"$f":"'Data Sheet'!F60/'Data Sheet'!F30","v":5.4827945776850884},{"$f":"'Data Sheet'!G60/'Data Sheet'!G30","v":4.0650124069478908},{"$f":"'Data Sheet'!H60/'Data Sheet'!H30","v":2.5858267716535432},{"$f":"'Data Sheet'!I60/'Data Sheet'!I30","v":2.0247933884297518},{"$f":"'Data Sheet'!J60/'Data Sheet'!J30","v":1.002017238217495},{"$f":"'Data Sheet'!K60/'Data Sheet'!K30","v":0.78822093378089708}]
["Total liability/Earning",{"$f":"('Data Sheet'!B59+'Data Sheet'!B60)/'Data Sheet'!B30","v":5.0406189555125733},{"$f":"('Data Sheet'!C59+'Data Sheet'!C60)/'Data Sheet'!C30","v":2.9827882960413081},{"$f":"('Data Sheet'!D59+'Data Sheet'!D60)/'Data Sheet'!D30","v":3.5942275042444827},{"$f":"('Data Sheet'!E59+'Data Sheet'!E60)/'Data Sheet'!E30","v":7.4242115971515767},{"$f":"('Data Sheet'!F59+'Data Sheet'!F60)/'Data Sheet'!F30","v":19.158498435870701},{"$f":"('Data Sheet'!G59+'Data Sheet'!G60)/'Data Sheet'!G30","v":11.173200992555831},{"$f":"('Data Sheet'!H59+'Data Sheet'!H60)/'Data Sheet'!H30","v":7.0003149606299209},{"$f":"('Data Sheet'!I59+'Data Sheet'!I60)/'Data Sheet'!I30","v":5.294273907910271},{"$f":"('Data Sheet'!J59+'Data Sheet'!J60)/'Data Sheet'!J30","v":3.1056299284797357},{"$f":"('Data Sheet'!K59+'Data Sheet'!K60)/'Data Sheet'!K30","v":2.0936832468721391}]
["Debt/Equity",{"$f":"'Data Sheet'!B59/KeyMetrics!B12","v":0.33412135539795118},{"$f":"'Data Sheet'!C59/KeyMetrics!C12","v":8.8160037217957662E-2},{"$f":"'Data Sheet'!D59/KeyMetrics!D12","v":0.19318701417466846},{"$f":"'Data Sheet'!E59/KeyMetrics!E12","v":0.73871150576232758},{"$f":"'Data Sheet'!F59/KeyMetrics!F12","v":2.0973932512394051},{"$f":"'Data Sheet'!G59/KeyMetrics!G12","v":1.7428814796787537},{"$f":"'Data Sheet'!H59/KeyMetrics!H12","v":1.2388191621000531},{"$f":"'Data Sheet'!I59/KeyMetrics!I12","v":0.75662568306010924},{"$f":"'Data Sheet'!J59/KeyMetrics!J12","v":0.57152110009466384},{"$f":"'Data Sheet'!K59/KeyMetrics!K12","v":0.43031014249790445}]
["Interest Coverage",{"$f":"KeyMetrics!B6/'Data Sheet'!B27","v":11.566265060240964},{"$f":"KeyMetrics!C6/'Data Sheet'!C27","v":18.73469387755102},{"$f":"KeyMetrics!D6/'Data Sheet'!D27","v":30.740740740740733},{"$f":"KeyMetrics!E6/'Data Sheet'!E27","v":13.943396226415095},{"$f":"KeyMetrics!F6/'Data Sheet'!F27","v":3.844758064516129},{"$f":"KeyMetrics!G6/'Data Sheet'!G27","v":2.8158212560386473},{"$f":"KeyMetrics!H6/'Data Sheet'!H27","v":3.7462857142857144},{"$f":"KeyMetrics!I6/'Data Sheet'!I27","v":4.8942598187311175},{"$f":"KeyMetrics!J6/'Data Sheet'!J27","v":7.7405622489959844},{"$f":"KeyMetrics!K6/'Data Sheet'!K27","v":13.141450313339302}]
["Working Capital/Sales",{"$f":"KeyMetrics!B13/'Data Sheet'!B17","v":0.39819312220711089},{"$f":"KeyMetrics!C13/'Data Sheet'!C17","v":0.30004031445273133},{"$f":"KeyMetrics!D13/'Data Sheet'!D17","v":0.29744739933781911},{"$f":"KeyMetrics!E13/'Data Sheet'!E17","v":0.18689679464600209},{"$f":"KeyMetrics!F13/'Data Sheet'!F17","v":0.31508180787299533},{"$f":"KeyMetrics!G13/'Data Sheet'!G17","v":0.22848895303652714},{"$f":"KeyMetrics!H13/'Data Sheet'!H17","v":0.19470401425666567},{"$f":"KeyMetrics!I13/'Data Sheet'!I17","v":0.22333281620531464},{"$f":"KeyMetrics!J13/'Data Sheet'!J17","v":0.29602263540824569},{"$f":"KeyMetrics!K13/'Data Sheet'!K17","v":0.34283694925094338},"Check for improving or deteriorating picture"]
["Inventory Turns",{"$f":"365/B27","v":9.1583629893238445},7.3063328424153173,7.9213197969543137,8.4949132256134057,4.9702093397745566,5.3430223935933547,7.6265899982575354,7.9508370044052858,7.3753875506797035,8.4138260592545393]
["Inventory Days",{"$f":"'Balance Sheet'!B21","v":39.854284048960558},{"$f":"'Balance Sheet'!C21","v":49.956661963313842},{"$f":"'Balance Sheet'!D21","v":46.078180070490234},{"$f":"'Balance Sheet'!E21","v":42.966889749911942},{"$f":"'Balance Sheet'!F21","v":73.437550623683791},{"$f":"'Balance Sheet'!G21","v":68.313395137115592},{"$f":"'Balance Sheet'!H21","v":47.858872718133846},{"$f":"'Balance Sheet'!I21","v":45.907116420292105},{"$f":"'Balance Sheet'!J21","v":49.48892481810833},{"$f":"'Balance Sheet'!K21","v":43.380977622960131}]
["Debtor Days",{"$f":"'Balance Sheet'!B22","v":78.928502040023318},{"$f":"'Balance Sheet'!C22","v":62.243499294497077},{"$f":"'Balance Sheet'!D22","v":62.100288369112469},{"$f":"'Balance Sheet'!E22","v":77.242691088411405},{"$f":"'Balance Sheet'!F22","v":88.732112965062925},{"$f":"'Balance Sheet'!G22","v":61.201426668146993},{"$f":"'Balance Sheet'!H22","v":66.321940185976374},{"$f":"'Balance Sheet'!I22","v":71.323884665676729},{"$f":"'Balance Sheet'!J22","v":70.905012126111558},{"$f":"'Balance Sheet'!K22","v":102.08833440611866}]
["Creditor Days",null,null,null,null,null,null,null,null,null,null,"Check back to see if Creditor policy change is impacting Working Cap cycle"]
["Cash Conversion Cycle"]
["Cash In/Cash Out Ratio",{"$f":"('Data Sheet'!B67+'Data Sheet'!B69)/'Data Sheet'!B60","v":1.7338830584707647},{"$f":"('Data Sheet'!C67+'Data Sheet'!C69)/'Data Sheet'!C60","v":1.4025110782865586},{"$f":"('Data Sheet'!D67+'Data Sheet'!D69)/'Data Sheet'!D60","v":1.3380503144654088},{"$f":"('Data Sheet'!E67+'Data Sheet'!E69)/'Data Sheet'!E60","v":0.93417945690672954},{"$f":"('Data Sheet'!F67+'Data Sheet'!F69)/'Data Sheet'!F60","v":0.93952073031570948},{"$f":"('Data Sheet'!G67+'Data Sheet'!G69)/'Data Sheet'!G60","v":0.79733854230252721},{"$f":"('Data Sheet'!H67+'Data Sheet'!H69)/'Data Sheet'!H60","v":1.0252131546894032},{"$f":"('Data Sheet'!I67+'Data Sheet'!I69)/'Data Sheet'!I60","v":1.3402332361516036},{"$f":"('Data Sheet'!J67+'Data Sheet'!J69)/'Data Sheet'!J60","v":2.2604319180087846},{"$f":"('Data Sheet'!K67+'Data Sheet'!K69)/'Data Sheet'!K60","v":2.9242482901019491},null,"  "]
["Current Ratio",{"$f":"'Data Sheet'!B65/'Data Sheet'!B60","v":4.0727136431784103},{"$f":"'Data Sheet'!C65/'Data Sheet'!C60","v":3.1986706056129988},{"$f":"'Data Sheet'!D65/'Data Sheet'!D60","v":3.1894654088050314},{"$f":"'Data Sheet'!E65/'Data Sheet'!E60","v":1.7830578512396691},{"$f":"'Data Sheet'!F65/'Data Sheet'!F60","v":2.1097375427919363},{"$f":"'Data Sheet'!G65/'Data Sheet'!G60","v":2.0050054938346964},{"$f":"'Data Sheet'!H65/'Data Sheet'!H60","v":2.0380024360535933},{"$f":"'Data Sheet'!I65/'Data Sheet'!I60","v":2.4689504373177846},{"$f":"'Data Sheet'!J65/'Data Sheet'!J60","v":4.3508418740849191},{"$f":"'Data Sheet'!K65/'Data Sheet'!K60","v":4.5054845786553104}," "]
["CFO/PAT",{"$f":"KeyMetrics!B18/KeyMetrics!B9","v":-0.43133462282398455},{"$f":"KeyMetrics!C18/KeyMetrics!C9","v":3.228915662650603},{"$f":"KeyMetrics!D18/KeyMetrics!D9","v":1.7096774193548387},{"$f":"KeyMetrics!E18/KeyMetrics!E9","v":1.2756866734486265},{"$f":"KeyMetrics!F18/KeyMetrics!F9","v":-0.78727841501564133},{"$f":"KeyMetrics!G18/KeyMetrics!G9","v":1.4153846153846155},{"$f":"KeyMetrics!H18/KeyMetrics!H9","v":1.8806299212598425},{"$f":"KeyMetrics!I18/KeyMetrics!I9","v":1.3792798110979927},{"$f":"KeyMetrics!J18/KeyMetrics!J9","v":0.28938199156427652},{"$f":"KeyMetrics!K18/KeyMetrics!K9","v":0.29305258874987283}]
[null,null,null,null,null,null,null,null,null,null,null," "]
["Gross Margin =Gross Profit/Sales",{"$f":"KeyMetrics!B4/'Data Sheet'!B17","v":0.27754031474645419},{"$f":"KeyMetrics!C4/'Data Sheet'!C17","v":0.28411610562386613},{"$f":"KeyMetrics!D4/'Data Sheet'!D17","v":0.37925878457759266},{"$f":"KeyMetrics!E4/'Data Sheet'!E17","v":0.29623106727721021},{"$f":"KeyMetrics!F4/'Data Sheet'!F17","v":0.24893352772827904},{"$f":"KeyMetrics!G4/'Data Sheet'!G17","v":0.28849783501720883},{"$f":"KeyMetrics!H4/'Data Sheet'!H17","v":0.35778747515364762},{"$f":"KeyMetrics!I4/'Data Sheet'!I17","v":0.34852950954101192},{"$f":"KeyMetrics!J4/'Data Sheet'!J17","v":0.31220695230396123},{"$f":"KeyMetrics!K4/'Data Sheet'!K17","v":0.34170105890222507}]
["EBIT/Sales",{"$f":"KeyMetrics!B6/'Data Sheet'!B17","v":9.3258208665241885E-2},{"$f":"KeyMetrics!C6/'Data Sheet'!C17","v":9.2521669018343078E-2},{"$f":"KeyMetrics!D6/'Data Sheet'!D17","v":8.8646801238919146E-2},{"$f":"KeyMetrics!E6/'Data Sheet'!E17","v":0.10412116942585418},{"$f":"KeyMetrics!F6/'Data Sheet'!F17","v":0.10297532264161133},{"$f":"KeyMetrics!G6/'Data Sheet'!G17","v":0.12942711224603087},{"$f":"KeyMetrics!H6/'Data Sheet'!H17","v":0.14978637848705706},{"$f":"KeyMetrics!I6/'Data Sheet'!I17","v":0.14361383834578134},{"$f":"KeyMetrics!J6/'Data Sheet'!J17","v":0.15581244947453518},{"$f":"KeyMetrics!K6/'Data Sheet'!K17","v":0.18526371587596074}]
["EBITDA/Sales",{"$f":"KeyMetrics!B7/'Data Sheet'!B17","v":0.10229259762968719},{"$f":"KeyMetrics!C7/'Data Sheet'!C17","v":0.10139084861923001},{"$f":"KeyMetrics!D7/'Data Sheet'!D17","v":0.10797821211150273},{"$f":"KeyMetrics!E7/'Data Sheet'!E17","v":0.11553363860514268},{"$f":"KeyMetrics!F7/'Data Sheet'!F17","v":0.14012635671472543},{"$f":"KeyMetrics!G7/'Data Sheet'!G17","v":0.17891639835683357},{"$f":"KeyMetrics!H7/'Data Sheet'!H17","v":0.19029450067399303},{"$f":"KeyMetrics!I7/'Data Sheet'!I17","v":0.18135679617029765},{"$f":"KeyMetrics!J7/'Data Sheet'!J17","v":0.18237671786580439},{"$f":"KeyMetrics!K7/'Data Sheet'!K17","v":0.20598740423813305}]
["Op Profit (Ex Other Income)/Sales",{"$f":"KeyMetrics!B8/'Data Sheet'!B17","v":6.226928307752088E-2},{"$f":"KeyMetrics!C8/'Data Sheet'!C17","v":6.4603910501914941E-2},{"$f":"KeyMetrics!D8/'Data Sheet'!D17","v":6.9956210616255468E-2},{"$f":"KeyMetrics!E8/'Data Sheet'!E17","v":0.11757661148291654},{"$f":"KeyMetrics!F8/'Data Sheet'!F17","v":0.13915438198606836},{"$f":"KeyMetrics!G8/'Data Sheet'!G17","v":0.17714000222049517},{"$f":"KeyMetrics!H8/'Data Sheet'!H17","v":0.18832963969933059},{"$f":"KeyMetrics!I8/'Data Sheet'!I17","v":0.18002703840783671},{"$f":"KeyMetrics!J8/'Data Sheet'!J17","v":0.17920776071139857},{"$f":"KeyMetrics!K8/'Data Sheet'!K17","v":0.1936314414448525}]
["Net Margin =PAT/Sales",{"$f":"KeyMetrics!B9/'Data Sheet'!B17","v":5.0223431124927144E-2},{"$f":"KeyMetrics!C9/'Data Sheet'!C17","v":5.855674259221931E-2},{"$f":"KeyMetrics!D9/'Data Sheet'!D17","v":6.2907187867136602E-2},{"$f":"KeyMetrics!E9/'Data Sheet'!E17","v":6.9249735822472708E-2},{"$f":"KeyMetrics!F9/'Data Sheet'!F17","v":5.1784653599006428E-2},{"$f":"KeyMetrics!G9/'Data Sheet'!G17","v":5.5928722105029423E-2},{"$f":"KeyMetrics!H9/'Data Sheet'!H17","v":7.2539925518060724E-2},{"$f":"KeyMetrics!I9/'Data Sheet'!I17","v":7.5086988320294326E-2},{"$f":"KeyMetrics!J9/'Data Sheet'!J17","v":8.8164915117219078E-2},{"$f":"KeyMetrics!K9/'Data Sheet'!K17","v":0.12407708909166634}]
["Op Cash Flow/Sales",{"$f":"KeyMetrics!B18/'Data Sheet'!B17","v":-2.1663104721196813E-2},{"$f":"KeyMetrics!C18/'Data Sheet'!C17","v":0.18907478330981659},{"$f":"KeyMetrics!D18/'Data Sheet'!D17","v":0.10755099861155613},{"$f":"KeyMetrics!E18/'Data Sheet'!E17","v":8.8340965128566401E-2},{"$f":"KeyMetrics!F18/'Data Sheet'!F17","v":-4.0768940007559804E-2},{"$f":"KeyMetrics!G18/'Data Sheet'!G17","v":7.9160652825580102E-2},{"$f":"KeyMetrics!H18/'Data Sheet'!H17","v":0.13642075441522539},{"$f":"KeyMetrics!I18/'Data Sheet'!I17","v":0.10356596706633275},{"$f":"KeyMetrics!J18/'Data Sheet'!J17","v":2.5513338722716248E-2},{"$f":"KeyMetrics!K18/'Data Sheet'!K17","v":3.6361112162861434E-2}]
["Free Cash Flow/Sales",{"$f":"KeyMetrics!B20/'Data Sheet'!B17","v":0},{"$f":"KeyMetrics!C20/'Data Sheet'!C17","v":0.17849223946784923},{"$f":"KeyMetrics!D20/'Data Sheet'!D17","v":-0.1001815657374773},{"$f":"KeyMetrics!E20/'Data Sheet'!E17","v":-0.21387812610073972},{"$f":"KeyMetrics!F20/'Data Sheet'!F17","v":-0.45882607052216651},{"$f":"KeyMetrics!G20/'Data Sheet'!G17","v":8.0770511824137387E-3},{"$f":"KeyMetrics!H20/'Data Sheet'!H17","v":0.1062852703968562},{"$f":"KeyMetrics!I20/'Data Sheet'!I17","v":7.0322023004809289E-2},{"$f":"KeyMetrics!J20/'Data Sheet'!J17","v":5.4486661277283709E-3},{"$f":"KeyMetrics!K20/'Data Sheet'!K17","v":-1.2911286963765098E-2}]
["EPA/Sales",{"$f":"KeyMetrics!B25/'Data Sheet'!B17","v":8.7519957713021212E-4},{"$f":"KeyMetrics!C25/'Data Sheet'!C17","v":1.9092989762031075E-2},{"$f":"KeyMetrics!D25/'Data Sheet'!D17","v":-4.4382322033057641E-4},{"$f":"KeyMetrics!E25/'Data Sheet'!E17","v":-2.3623766016243829E-3},{"$f":"KeyMetrics!F25/'Data Sheet'!F17","v":-5.5404733254398202E-2},{"$f":"KeyMetrics!G25/'Data Sheet'!G17","v":1.1780877002548613E-2},{"$f":"KeyMetrics!H25/'Data Sheet'!H17","v":3.7674768663809456E-2},{"$f":"KeyMetrics!I25/'Data Sheet'!I17","v":3.1329945001432144E-2},{"$f":"KeyMetrics!J25/'Data Sheet'!J17","v":4.0065043815066592E-2},{"$f":"KeyMetrics!K25/'Data Sheet'!K17","v":6.9702088453031621E-2}]
[]
["Sales/Invested Capital =Capital Turns",{"$f":"'Data Sheet'!B17/KeyMetrics!B14","v":2.2180564533505711},{"$f":"'Data Sheet'!C17/KeyMetrics!C14","v":2.805995475113122},{"$f":"'Data Sheet'!D17/KeyMetrics!D14","v":1.8330070477682068},{"$f":"'Data Sheet'!E17/KeyMetrics!E14","v":1.5592047451669595},{"$f":"'Data Sheet'!F17/KeyMetrics!F14","v":0.9575491209927609},{"$f":"'Data Sheet'!G17/KeyMetrics!G14","v":1.6001776593382191},{"$f":"'Data Sheet'!H17/KeyMetrics!H14","v":1.9582569012572144},{"$f":"'Data Sheet'!I17/KeyMetrics!I14","v":1.9035987005864237},{"$f":"'Data Sheet'!J17/KeyMetrics!J14","v":1.9614372244949736},{"$f":"'Data Sheet'!K17/KeyMetrics!K14","v":1.8577491207502932}]
["Sales/Fixed Assets= Fixed Asset Turns",{"$f":"'Data Sheet'!B17/'Data Sheet'!B62","v":18.992619926199261},{"$f":"'Data Sheet'!C17/'Data Sheet'!C62","v":17.749552772808588},{"$f":"'Data Sheet'!D17/'Data Sheet'!D62","v":4.693233082706767},{"$f":"'Data Sheet'!E17/'Data Sheet'!E62","v":8.7407635467980302},{"$f":"'Data Sheet'!F17/'Data Sheet'!F62","v":1.3712699000370232},{"$f":"'Data Sheet'!G17/'Data Sheet'!G62","v":2.5325460424574722},{"$f":"'Data Sheet'!H17/'Data Sheet'!H62","v":3.2037037037037037},{"$f":"'Data Sheet'!I17/'Data Sheet'!I62","v":3.3245652814618332},{"$f":"'Data Sheet'!J17/'Data Sheet'!J62","v":4.7202930626574062},{"$f":"'Data Sheet'!K17/'Data Sheet'!K62","v":5.3637286758732738}]
["Sales/Total Assets= Asset Turns",{"$f":"'Data Sheet'!B17/KeyMetrics!B16","v":1.6051769842507408},{"$f":"'Data Sheet'!C17/KeyMetrics!C16","v":1.6448938992042441},{"$f":"'Data Sheet'!D17/KeyMetrics!D16","v":1.4424587890925897},{"$f":"'Data Sheet'!E17/KeyMetrics!E16","v":1.127392582003018},{"$f":"'Data Sheet'!F17/KeyMetrics!F16","v":0.75201007065702918},{"$f":"'Data Sheet'!G17/KeyMetrics!G16","v":1.1723285175061824},{"$f":"'Data Sheet'!H17/KeyMetrics!H16","v":1.3049791293977342},{"$f":"'Data Sheet'!I17/KeyMetrics!I16","v":1.3850569420143046},{"$f":"'Data Sheet'!J17/KeyMetrics!J16","v":1.671350591795925},{"$f":"'Data Sheet'!K17/KeyMetrics!K16","v":1.5718338358990638}]
["Net Margin*Asset Turns= RoA",{"$f":"B39*B46","v":8.0617495711835352E-2},{"$f":"C39*C46","v":9.6319628647214856E-2},9.0741026036049915E-2,7.8071638471924387E-2,3.8942581011938607E-2,6.5566835871404397E-2,9.4663088849135366E-2,0.10399975442797067,0.1473544830568016,0.1950285668941438,"Check back what is really driving RoA (Net Margins or Asset Turns, or both)"]
["Net Margin*Asset Turn*Fin Leverage= RoE",{"$f":"B39*B46*B19","v":0.13580246913580249},0.13514770876948126,0.13465935070873342,0.18571698469676931,0.15336638413561493,0.24519347773180819,0.28062577337811556,0.23142076502732245,0.27168551641672062,0.32962279966471081,"Check back what is really driving RoE (Net Margins, Asset Turns, or Financial Leverage)"]
["RoCE",{"$f":"KeyMetrics!B6/KeyMetrics!B15","v":0.18901358535144713},{"$f":"KeyMetrics!C6/KeyMetrics!C15","v":0.19623770842240273},{"$f":"KeyMetrics!D6/KeyMetrics!D15","v":0.15903429775819122},{"$f":"KeyMetrics!E6/KeyMetrics!E15","v":0.16059980441160493},{"$f":"KeyMetrics!F6/KeyMetrics!F15","v":9.8461379595208592E-2},{"$f":"KeyMetrics!G6/KeyMetrics!G15","v":0.20686748591455567},{"$f":"KeyMetrics!H6/KeyMetrics!H15","v":0.25882352941176473},{"$f":"KeyMetrics!I6/KeyMetrics!I15","v":0.25197340280748143},{"$f":"KeyMetrics!J6/KeyMetrics!J15","v":0.30552913575550061},{"$f":"KeyMetrics!K6/KeyMetrics!K15","v":0.34410089312923414}]
["EBIT Margin*Cap Turns*(1-Tax rate)= RoIC",{"$f":"B36*B44*(1-KeyMetrics!B21)","v":0.12194124207002335},{"$f":"C36*C44*(1-KeyMetrics!C21)","v":0.17357484287864033},{"$f":"D36*D44*(1-KeyMetrics!D21)","v":0.11918646890917088},{"$f":"E36*E44*(1-KeyMetrics!E21)","v":0.11631657119287585},{"$f":"F36*F44*(1-KeyMetrics!F21)","v":6.6947246373412608E-2},{"$f":"G36*G44*(1-KeyMetrics!G21)","v":0.13885149618688972},{"$f":"H36*H44*(1-KeyMetrics!H21)","v":0.1937768757391739},{"$f":"I36*I44*(1-KeyMetrics!I21)","v":0.17963964259417037},{"$f":"J36*J44*(1-KeyMetrics!J21)","v":0.19858506833989373},{"$f":"K36*K44*(1-KeyMetrics!K21)","v":0.24948899353807866},"Check back what is really driving RoIC (Op Margins or Capital Turns, or both)"]
[]
["Altman Z-Score",{"$f":"KeyMetrics!B46","v":3.1580684900271447},{"$f":"KeyMetrics!C46","v":3.2062200112068964},{"$f":"KeyMetrics!D46","v":2.8467195201240179},{"$f":"KeyMetrics!E46","v":2.1404850026855753},{"$f":"KeyMetrics!F46","v":1.4796902318687568},{"$f":"KeyMetrics!G46","v":2.3535580685814548},{"$f":"KeyMetrics!H46","v":3.0500806890846754},{"$f":"KeyMetrics!I46","v":3.3138731420311558},{"$f":"KeyMetrics!J46","v":5.3909800423600647},{"$f":"KeyMetrics!K46","v":5.9862754187926015}]
["Dividend Payout",{"$f":"'Data Sheet'!B31/'Data Sheet'!B30","v":8.1237911025145063E-2},{"$f":"'Data Sheet'!C31/'Data Sheet'!C30","v":0.13253012048192772},{"$f":"'Data Sheet'!D31/'Data Sheet'!D30","v":8.6587436332767415E-2},{"$f":"'Data Sheet'!E31/'Data Sheet'!E30","v":5.188199389623601E-2},{"$f":"'Data Sheet'!F31/'Data Sheet'!F30","v":0},{"$f":"'Data Sheet'!G31/'Data Sheet'!G30","v":2.0843672456575684E-2},{"$f":"'Data Sheet'!H31/'Data Sheet'!H30","v":2.0157480314960629E-2},{"$f":"'Data Sheet'!I31/'Data Sheet'!I30","v":1.5053128689492325E-2},{"$f":"'Data Sheet'!J31/'Data Sheet'!J30","v":1.1736658719970658E-2},{"$f":"'Data Sheet'!K31/'Data Sheet'!K30","v":6.5100193266198758E-3}]
["Cash/Assets",{"$f":"'Data Sheet'!B69/'Data Sheet'!B61","v":1.3566193669109623E-2},{"$f":"'Data Sheet'!C69/'Data Sheet'!C61","v":3.4316976127320951E-2},{"$f":"'Data Sheet'!D69/'Data Sheet'!D61","v":1.6792481898012634E-2},{"$f":"'Data Sheet'!E69/'Data Sheet'!E61","v":1.2786911285839092E-2},{"$f":"'Data Sheet'!F69/'Data Sheet'!F61","v":1.7786079753106473E-2},{"$f":"'Data Sheet'!G69/'Data Sheet'!G61","v":1.5944292594038789E-2},{"$f":"'Data Sheet'!H69/'Data Sheet'!H61","v":1.3834227787716159E-2},{"$f":"'Data Sheet'!I69/'Data Sheet'!I61","v":1.1572581882923537E-2},{"$f":"'Data Sheet'!J69/'Data Sheet'!J61","v":9.0796087121007407E-3},{"$f":"'Data Sheet'!K69/'Data Sheet'!K61","v":9.8992223456594204E-3}]
["EBIT/Invested Capital",{"$f":"KeyMetrics!B6/KeyMetrics!B14","v":0.20685197155785393},{"$f":"KeyMetrics!C6/KeyMetrics!C14","v":0.25961538461538464},{"$f":"KeyMetrics!D6/KeyMetrics!D14","v":0.16249021143304618},{"$f":"KeyMetrics!E6/KeyMetrics!E14","v":0.16234622144112482},{"$f":"KeyMetrics!F6/KeyMetrics!F14","v":9.8603929679420874E-2},{"$f":"KeyMetrics!G6/KeyMetrics!G14","v":0.2071063735287586},{"$f":"KeyMetrics!H6/KeyMetrics!H14","v":0.29332020938660464},{"$f":"KeyMetrics!I6/KeyMetrics!I14","v":0.27338311606125804},{"$f":"KeyMetrics!J6/KeyMetrics!J14","v":0.30561633843909558},{"$f":"KeyMetrics!K6/KeyMetrics!K14","v":0.34417350527549823},"Check back the significant role of EBIT/Invested Capital "]
["EPA",{"$f":"KeyMetrics!B25","v":9.0093044469784028E-2},{"$f":"KeyMetrics!C25","v":1.8944064441887234},{"$f":"KeyMetrics!D25","v":-4.1555168119551865E-2},{"$f":"KeyMetrics!E25","v":-0.33533935860058112},{"$f":"KeyMetrics!F25","v":-10.260402551382002},{"$f":"KeyMetrics!G25","v":4.2444143664782139},{"$f":"KeyMetrics!H25","v":16.489869496462759},{"$f":"KeyMetrics!I25","v":14.136384484096197},{"$f":"KeyMetrics!J25","v":24.780229599618689},{"$f":"KeyMetrics!K25","v":55.227055743990547},"Check back what is really driving EPA (Invested Capital or RoIC, or both)"]
["MktCap",{"$f":"KeyMetrics!B27","v":20.114887109067997},{"$f":"KeyMetrics!C27","v":35.17531846},{"$f":"KeyMetrics!D27","v":38.014273418749994},{"$f":"KeyMetrics!E27","v":56.500777813567993},{"$f":"KeyMetrics!F27","v":54.702527499999995},{"$f":"KeyMetrics!G27","v":137.88410939408797},{"$f":"KeyMetrics!H27","v":371.901771865},{"$f":"KeyMetrics!I27","v":411.44742246581598},{"$f":"KeyMetrics!J27","v":1272.1851241262759},{"$f":"KeyMetrics!K27","v":2130.1978551749576}]
["MktCap Change",null,{"$f":"C57-B57","v":15.060431350932003},{"$f":"D57-C57","v":2.8389549587499943},18.486504394817999,-1.7982503135679977,83.181581894087969,234.01766247091203,39.545650600815975,860.73770166045995,858.01273104868164]
["MktCap Change - EPA",null,{"$f":"C58-C56","v":13.16602490674328},2.8805101268695461,18.82184375341858,8.4621522378140046,78.937167527609759,217.52779297444926,25.409266116719778,835.95747206084127,802.78567530469104]
[]
["Capex/Net Profits 10 yr",{"$f":"SUM(KeyMetrics!B$19:K$19)/SUM(KeyMetrics!B$9:K$9)","v":0.89509293950747537}]
["Capex/Net Profits 7 yr",{"$f":"SUM(KeyMetrics!E$19:K$19)/SUM(KeyMetrics!E$9:K$9)","v":0.87416679584560553}]
["Capex/Net Profits 5 yr",{"$f":"SUM(KeyMetrics!G$19:K$19)/SUM(KeyMetrics!G$9:K$9)","v":0.44107786438689117}]
["Capex/Net Profits 3 yr",{"$f":"SUM(KeyMetrics!I$19:K$19)/SUM(KeyMetrics!I$9:K$9)","v":0.35588046272493568}]
["Capex/Depreciation 10 yr",{"$f":"SUM(KeyMetrics!B$19:K$19)/SUM('Data Sheet'!B26:K26)","v":2.5222427224272241}]

{"sheet":"Data Sheet","index":5,"n_rows":93,"n_cols":11,"rows_kept":93,"cut":false,"hidden":true,"merged":[[0,4,0,10],[1,4,1,10]]}
["COMPANY NAME","BHARAT RASAYAN LTD",null,null,{"$f":"IF(B2<>B3, \"A NEW VERSION OF THE WORKSHEET IS AVAILABLE\", \"\")","v":""}]
["LATEST VERSION",2.1,null,null,"PLEASE DO NOT MAKE ANY CHANGES TO THIS SHEET"]
["CURRENT VERSION",2.1]
[]
["META"]
["Number of shares",{"$f":"IF(B9>0, B9/B8, 0)","v":0.42500060852420707}]
["Face Value",10]
["Current Price",4108.3]
["Market Capitalization",1746.03]
[]
[]
[]
[]
[]
["PROFIT & LOSS"]
["Report Date","2009-03-31","2010-03-31","2011-03-31","2012-03-31","2013-03-31","2014-03-31","2015-03-31","2016-03-31","2017-03-31","2018-03-31"]
["Sales",102.94,99.22,93.63,141.94999999999999,185.19,360.28,437.69,451.21,618.5,792.33]
["Raw Material Cost",74.37,71.03,58.12,99.9,139.09,256.33999999999997,281.08999999999997,293.95,425.4,521.59]
["Change in Inventory",-0.22,0.59,-5.34,6.09,13.65,21.25,-6.14,1.71,15.72,-0.76]
["Power and Fuel",1.52,1.59,2.96,3,5.71,9.8000000000000007,10.4,12.77,15.31,17.899999999999999]
["Other Mfr. Exp",9.93,8.4,4.18,11.61,9.4700000000000006,13.41,17.940000000000001,20.82,24.72,28.74]
["Employee Cost",4.21,4.93,6.97,7.29,11.12,20.440000000000001,23.23,27.19,31.51,35.25]
["Selling and admin",5.64,7.2,7.42,8.61,10.039999999999999,14.77,16.920000000000002,20.41,24.57,32.15]
["Other Expenses",0.68,0.25,2.09,0.94,-2.3199999999999998,3.01,-0.43,-3.39,2.08,2.5299999999999998]
["Other Income",4.12,3.65,3.56,-0.28999999999999998,0.18,0.64,0.86,0.6,1.96,9.7899999999999991]
["Depreciation",0.93,0.88,1.81,1.62,6.88,17.829999999999998,17.73,17.03,16.43,16.420000000000002]
["Interest",0.83,0.49,0.27,1.06,4.96,16.559999999999999,17.5,13.24,12.45,11.17]
["Profit before tax",8.77,8.69,8.0299999999999994,13.72,14.11,30.07,48.06,51.56,83.92,135.62]
["Tax",3.6,2.88,2.14,3.89,4.53,9.91,16.309999999999999,17.68,29.39,37.31]
["Net profit",5.17,5.81,5.89,9.83,9.59,20.149999999999999,31.75,33.880000000000003,54.53,98.31]
["Dividend Amount",0.42,0.77,0.51,0.51,null,0.42,0.64,0.51,0.64,0.64]
[]
[]
[]
[]
[]
[]
[]
[]
["Quarters"]
["Report Date","2016-12-31","2017-03-31","2017-06-30","2017-09-30","2017-12-31","2018-03-31","2018-06-30","2018-09-30","2018-12-31","2019-03-31"]
["Sales",130.15,132.51,169.15,244.06,188.66,193.44,245.12,285.27,189.56,272.23]
["Expenses",107.56,101.01,139.41,198.74,143.77000000000001,155.19999999999999,204.1,226.5,150.13,224.35]
["Other Income",2.5,-5.12,0.68,-0.18,-2.62,6.62,1.78,0.56000000000000005,-0.12,-1.47]
["Depreciation",4.0999999999999996,4.29,3.88,4.03,4.18,4.33,4.03,4.25,4.3499999999999996,4.26]
["Interest",3.99,2.46,2.8,2.93,2.73,2.1800000000000002,3.09,4.01,4.13,4.59]
["Profit before tax",17,19.63,23.74,38.18,35.36,38.35,35.68,51.07,30.83,37.56]
["Tax",5.76,7.52,8.11,14.1,12.27,2.83,10.7,15.28,9.48,8.15]
["Net profit",11.24,12.11,15.63,24.08,23.09,35.520000000000003,24.98,35.79,21.35,29.41]
["Operating Profit",22.59,31.5,29.74,45.32,44.89,38.24,41.02,58.77,39.43,47.88]
[]
[]
[]
[]
["BALANCE SHEET"]
["Report Date","2009-03-31","2010-03-31","2011-03-31","2012-03-31","2013-03-31","2014-03-31","2015-03-31","2016-03-31","2017-03-31","2018-03-31"]
["Equity Share Capital",4.25,4.25,4.25,4.25,4.25,4.25,4.25,4.25,4.25,4.25]
["Reserves",33.82,38.74,39.49,48.68,58.28,77.930000000000007,108.89,142.15,196.46,294]
["Borrowings",12.72,3.79,8.4499999999999993,39.1,131.15,143.22999999999999,140.16,110.77,114.71,128.34]
["Other Liabilities",13.34,13.54,12.72,33.880000000000003,52.58,81.91,82.1,68.599999999999994,54.64,77.489999999999995]
["Total",64.13,60.32,64.91,125.91,246.26,307.32,335.4,325.77,370.06,504.08]
["Net Block",5.42,5.59,19.95,16.239999999999998,135.05000000000001,142.26,136.62,135.72,131.03,147.72]
["Capital Work in Progress",null,null,3.28,48.27,null,0.56999999999999995,1.67,0.54,1.21,7.14]
["Investments",4.38,11.42,1.1100000000000001,0.99,0.28000000000000003,0.26,29.79,20.14,0.09,0.09]
["Other Assets",54.33,43.31,40.57,60.41,110.93,164.23,167.32,169.37,237.73,349.13]
["Total",64.13,60.32,64.91,125.91,246.26,307.32,335.4,325.77,370.06,504.08]
["Receivables",22.26,16.920000000000002,15.93,30.04,45.02,60.41,79.53,88.17,120.15,221.61]
["Inventory",11.24,13.58,11.82,16.71,37.26,67.430000000000007,57.39,56.75,83.86,94.17]
["Cash & Bank",0.87,2.0699999999999998,1.0900000000000001,1.61,4.38,4.9000000000000004,4.6399999999999997,3.77,3.36,4.99]
["No. of Equity Shares",4248740,4248740,4248740,4248740,4248740,4248740,4248740,4248740,4248740,4248740]
["New Bonus Shares"]
["Face value",10,10,10,10,10,10,10,10,10,10]
[]
[]
[]
[]
[]
[]
[]
["CASH FLOW:"]
["Report Date","2009-03-31","2010-03-31","2011-03-31","2012-03-31","2013-03-31","2014-03-31","2015-03-31","2016-03-31","2017-03-31","2018-03-31"]
["Cash from Operating Activity",-2.23,18.760000000000002,10.07,12.54,-7.55,28.52,59.71,46.73,15.78,28.81]
["Cash from Investing Activity",-3.99,-8.0500000000000007,-6.93,-41.81,-76.69,-25.36,-40.97,-4.99,7.77,-30.85]
["Cash from Financing Activity",4.8600000000000003,-9.6199999999999992,-5.23,29.79,87.01,-2.65,-18.98,-42.62,-23.9,2.23]
["Net Cash Flow",-1.36,1.0900000000000001,-2.09,0.52,2.77,0.51,-0.25,-0.88,-0.34,0.18]
[]
[]
[]
[]
["PRICE:",47.343181999999999,82.79,89.471874999999997,132.98243199999999,128.75,324.52941199999998,875.32249999999999,968.398684,2994.2644740000001,5013.7166669999997]
[]
["DERIVED:"]
["Adjusted Equity Shares in Cr",{"$f":"IF($B7>0,(B70*B72/$B7)+SUM(C71:$K71),0)/10000000","v":0.42487399999999997},{"$f":"IF($B7>0,(C70*C72/$B7)+SUM(D71:$K71),0)/10000000","v":0.42487399999999997},{"$f":"IF($B7>0,(D70*D72/$B7)+SUM(E71:$K71),0)/10000000","v":0.42487399999999997},{"$f":"IF($B7>0,(E70*E72/$B7)+SUM(F71:$K71),0)/10000000","v":0.42487399999999997},{"$f":"IF($B7>0,(F70*F72/$B7)+SUM(G71:$K71),0)/10000000","v":0.42487399999999997},{"$f":"IF($B7>0,(G70*G72/$B7)+SUM(H71:$K71),0)/10000000","v":0.42487399999999997},{"$f":"IF($B7>0,(H70*H72/$B7)+SUM(I71:$K71),0)/10000000","v":0.42487399999999997},{"$f":"IF($B7>0,(I70*I72/$B7)+SUM(J71:$K71),0)/10000000","v":0.42487399999999997},{"$f":"IF($B7>0,(J70*J72/$B7)+SUM(K71:$K71),0)/10000000","v":0.42487399999999997},{"$f":"IF($B7>0,(K70*K72/$B7),0)/10000000","v":0.42487399999999997}]

{"sheet":"KeyMetrics","index":6,"n_rows":111,"n_cols":17,"rows_kept":111,"cut":false,"hidden":false,"merged":[[50,0,50,11],[1,15,1,16]]}
[{"$f":"'Data Sheet'!B1","v":"BHARAT RASAYAN LTD"}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"PETER LYNCH KPIs"]
[null,{"$f":"'Data Sheet'!B16","v":"2009-03-31"},{"$f":"'Data Sheet'!C16","v":"2010-03-31"},{"$f":"'Data Sheet'!D16","v":"2011-03-31"},{"$f":"'Data Sheet'!E16","v":"2012-03-31"},{"$f":"'Data Sheet'!F16","v":"2013-03-31"},{"$f":"'Data Sheet'!G16","v":"2014-03-31"},{"$f":"'Data Sheet'!H16","v":"2015-03-31"},{"$f":"'Data Sheet'!I16","v":"2016-03-31"},{"$f":"'Data Sheet'!J16","v":"2017-03-31"},{"$f":"'Data Sheet'!K16","v":"2018-03-31"},null,null,null,null,"Current Price",{"$f":"'Data Sheet'!B8","v":4108.3}]
["Gross Profit",{"$f":"'Data Sheet'!B17-'Data Sheet'!B18","v":28.569999999999993},{"$f":"'Data Sheet'!C17-'Data Sheet'!C18","v":28.189999999999998},{"$f":"'Data Sheet'!D17-'Data Sheet'!D18","v":35.51},{"$f":"'Data Sheet'!E17-'Data Sheet'!E18","v":42.049999999999983},{"$f":"'Data Sheet'!F17-'Data Sheet'!F18","v":46.099999999999994},{"$f":"'Data Sheet'!G17-'Data Sheet'!G18","v":103.94},{"$f":"'Data Sheet'!H17-'Data Sheet'!H18","v":156.60000000000002},{"$f":"'Data Sheet'!I17-'Data Sheet'!I18","v":157.26},{"$f":"'Data Sheet'!J17-'Data Sheet'!J18","v":193.10000000000002},{"$f":"'Data Sheet'!K17-'Data Sheet'!K18","v":270.74},null,null,null,null,"Cash Held Per Share",{"$f":"KeyMetrics!K94/'Data Sheet'!B6","v":11.952924062014972}]
["Gross Margin",{"$f":"B4/'Data Sheet'!B17","v":0.27754031474645419},{"$f":"C4/'Data Sheet'!C17","v":0.28411610562386613},{"$f":"D4/'Data Sheet'!D17","v":0.37925878457759266},{"$f":"E4/'Data Sheet'!E17","v":0.29623106727721021},{"$f":"F4/'Data Sheet'!F17","v":0.24893352772827904},{"$f":"G4/'Data Sheet'!G17","v":0.28849783501720883},{"$f":"H4/'Data Sheet'!H17","v":0.35778747515364762},{"$f":"I4/'Data Sheet'!I17","v":0.34852950954101192},{"$f":"J4/'Data Sheet'!J17","v":0.31220695230396123},{"$f":"K4/'Data Sheet'!K17","v":0.34170105890222507},null,null,null,null,"Dividend Paid",{"$f":"KeyMetrics!K91/'Data Sheet'!B6","v":1.5058801967892879}]
["EBIT",{"$f":"'Data Sheet'!B28+'Data Sheet'!B27","v":9.6},{"$f":"'Data Sheet'!C28+'Data Sheet'!C27","v":9.18},{"$f":"'Data Sheet'!D28+'Data Sheet'!D27","v":8.2999999999999989},{"$f":"'Data Sheet'!E28+'Data Sheet'!E27","v":14.780000000000001},{"$f":"'Data Sheet'!F28+'Data Sheet'!F27","v":19.07},{"$f":"'Data Sheet'!G28+'Data Sheet'!G27","v":46.629999999999995},{"$f":"'Data Sheet'!H28+'Data Sheet'!H27","v":65.56},{"$f":"'Data Sheet'!I28+'Data Sheet'!I27","v":64.8},{"$f":"'Data Sheet'!J28+'Data Sheet'!J27","v":96.37},{"$f":"'Data Sheet'!K28+'Data Sheet'!K27","v":146.79},null,null,null,null,"Dividend Payout (%)",{"$f":"KeyMetrics!K92","v":6.5100193266198758E-3}]
["EBITDA",{"$f":"KeyMetrics!B6+'Data Sheet'!B26","v":10.53},{"$f":"KeyMetrics!C6+'Data Sheet'!C26","v":10.06},{"$f":"KeyMetrics!D6+'Data Sheet'!D26","v":10.11},{"$f":"KeyMetrics!E6+'Data Sheet'!E26","v":16.400000000000002},{"$f":"KeyMetrics!F6+'Data Sheet'!F26","v":25.95},{"$f":"KeyMetrics!G6+'Data Sheet'!G26","v":64.459999999999994},{"$f":"KeyMetrics!H6+'Data Sheet'!H26","v":83.29},{"$f":"KeyMetrics!I6+'Data Sheet'!I26","v":81.83},{"$f":"KeyMetrics!J6+'Data Sheet'!J26","v":112.80000000000001},{"$f":"KeyMetrics!K6+'Data Sheet'!K26","v":163.20999999999998},null,null,null,null,"Current EPS",{"$f":"KeyMetrics!K65/'Data Sheet'!B6","v":231.3173158536795}]
["Operating Profit (excl Other Income)",{"$f":"B7-'Data Sheet'!B25","v":6.4099999999999993},{"$f":"C7-'Data Sheet'!C25","v":6.41},{"$f":"D7-'Data Sheet'!D25","v":6.5499999999999989},{"$f":"E7-'Data Sheet'!E25","v":16.690000000000001},{"$f":"F7-'Data Sheet'!F25","v":25.77},{"$f":"G7-'Data Sheet'!G25","v":63.819999999999993},{"$f":"H7-'Data Sheet'!H25","v":82.43},{"$f":"I7-'Data Sheet'!I25","v":81.23},{"$f":"J7-'Data Sheet'!J25","v":110.84000000000002},{"$f":"K7-'Data Sheet'!K25","v":153.41999999999999},null,null,null,null,"Cash EPS",{"$f":"KeyMetrics!K104/'Data Sheet'!B6","v":67.788138233592775}]
["PAT",{"$f":"'Data Sheet'!B30","v":5.17},{"$f":"'Data Sheet'!C30","v":5.81},{"$f":"'Data Sheet'!D30","v":5.89},{"$f":"'Data Sheet'!E30","v":9.83},{"$f":"'Data Sheet'!F30","v":9.59},{"$f":"'Data Sheet'!G30","v":20.149999999999999},{"$f":"'Data Sheet'!H30","v":31.75},{"$f":"'Data Sheet'!I30","v":33.880000000000003},{"$f":"'Data Sheet'!J30","v":54.53},{"$f":"'Data Sheet'!K30","v":98.31},null,null,null,null,"Cash Yield on CMP",{"$f":"Q8/Q3","v":1.6500289227561953E-2}]
["Dividend",{"$f":"'Data Sheet'!B31","v":0.42},{"$f":"'Data Sheet'!C31","v":0.77},{"$f":"'Data Sheet'!D31","v":0.51},{"$f":"'Data Sheet'!E31","v":0.51},{"$f":"'Data Sheet'!F31","v":0},{"$f":"'Data Sheet'!G31","v":0.42},{"$f":"'Data Sheet'!H31","v":0.64},{"$f":"'Data Sheet'!I31","v":0.51},{"$f":"'Data Sheet'!J31","v":0.64},{"$f":"'Data Sheet'!K31","v":0.64}]
[null,{"$f":"B3","v":"2009-03-31"},"2010-03-31","2011-03-31","2012-03-31","2013-03-31","2014-03-31","2015-03-31","2016-03-31","2017-03-31","2018-03-31",null,null,null,null,"A) NET PROFIT MARGIN",{"$f":"KeyMetrics!K66","v":0.12407708909166634}]
["Networth",{"$f":"'Data Sheet'!B57+'Data Sheet'!B58","v":38.07},{"$f":"'Data Sheet'!C57+'Data Sheet'!C58","v":42.99},{"$f":"'Data Sheet'!D57+'Data Sheet'!D58","v":43.74},{"$f":"'Data Sheet'!E57+'Data Sheet'!E58","v":52.93},{"$f":"'Data Sheet'!F57+'Data Sheet'!F58","v":62.53},{"$f":"'Data Sheet'!G57+'Data Sheet'!G58","v":82.18},{"$f":"'Data Sheet'!H57+'Data Sheet'!H58","v":113.14},{"$f":"'Data Sheet'!I57+'Data Sheet'!I58","v":146.4},{"$f":"'Data Sheet'!J57+'Data Sheet'!J58","v":200.71},{"$f":"'Data Sheet'!K57+'Data Sheet'!K58","v":298.25},null,null,null,null,"B) ASSET TURNOVER",{"$f":"KeyMetrics!K45","v":1.5718338358990638}]
["Working Capital",{"$f":"'Data Sheet'!B65-'Data Sheet'!B60","v":40.989999999999995},{"$f":"'Data Sheet'!C65-'Data Sheet'!C60","v":29.770000000000003},{"$f":"'Data Sheet'!D65-'Data Sheet'!D60","v":27.85},{"$f":"'Data Sheet'!E65-'Data Sheet'!E60","v":26.529999999999994},{"$f":"'Data Sheet'!F65-'Data Sheet'!F60","v":58.350000000000009},{"$f":"'Data Sheet'!G65-'Data Sheet'!G60","v":82.32},{"$f":"'Data Sheet'!H65-'Data Sheet'!H60","v":85.22},{"$f":"'Data Sheet'!I65-'Data Sheet'!I60","v":100.77000000000001},{"$f":"'Data Sheet'!J65-'Data Sheet'!J60","v":183.08999999999997},{"$f":"'Data Sheet'!K65-'Data Sheet'!K60","v":271.64},null,null,null,null,"C) LEVERAGE",{"$f":"(KeyMetrics!K96+KeyMetrics!K97)/KeyMetrics!K97","v":1.4303101424979046}]
["Invested Capital",{"$f":"'Data Sheet'!B62+'Data Sheet'!B63+KeyMetrics!B13","v":46.41},{"$f":"'Data Sheet'!C62+'Data Sheet'!C63+KeyMetrics!C13","v":35.36},{"$f":"'Data Sheet'!D62+'Data Sheet'!D63+KeyMetrics!D13","v":51.08},{"$f":"'Data Sheet'!E62+'Data Sheet'!E63+KeyMetrics!E13","v":91.039999999999992},{"$f":"'Data Sheet'!F62+'Data Sheet'!F63+KeyMetrics!F13","v":193.40000000000003},{"$f":"'Data Sheet'!G62+'Data Sheet'!G63+KeyMetrics!G13","v":225.14999999999998},{"$f":"'Data Sheet'!H62+'Data Sheet'!H63+KeyMetrics!H13","v":223.51},{"$f":"'Data Sheet'!I62+'Data Sheet'!I63+KeyMetrics!I13","v":237.03},{"$f":"'Data Sheet'!J62+'Data Sheet'!J63+KeyMetrics!J13","v":315.33},{"$f":"'Data Sheet'!K62+'Data Sheet'!K63+KeyMetrics!K13","v":426.5},null,null,null,null,"ROE = A X B X C",{"$f":"Q11*Q12*Q13","v":0.2789513373055249}]
["Capital Employed",{"$f":"B12+'Data Sheet'!B59","v":50.79},{"$f":"C12+'Data Sheet'!C59","v":46.78},{"$f":"D12+'Data Sheet'!D59","v":52.19},{"$f":"E12+'Data Sheet'!E59","v":92.03},{"$f":"F12+'Data Sheet'!F59","v":193.68},{"$f":"G12+'Data Sheet'!G59","v":225.41},{"$f":"H12+'Data Sheet'!H59","v":253.3},{"$f":"I12+'Data Sheet'!I59","v":257.17},{"$f":"J12+'Data Sheet'!J59","v":315.42},{"$f":"K12+'Data Sheet'!K59","v":426.59000000000003}]
["Total Assets",{"$f":"'Data Sheet'!B61","v":64.13},{"$f":"'Data Sheet'!C61","v":60.32},{"$f":"'Data Sheet'!D61","v":64.91},{"$f":"'Data Sheet'!E61","v":125.91},{"$f":"'Data Sheet'!F61","v":246.26},{"$f":"'Data Sheet'!G61","v":307.32},{"$f":"'Data Sheet'!H61","v":335.4},{"$f":"'Data Sheet'!I61","v":325.77},{"$f":"'Data Sheet'!J61","v":370.06},{"$f":"'Data Sheet'!K61","v":504.08},null,null,null,null,"Price/Earnings",{"$f":"Q3/Q7","v":17.760451632590783}]
[null,{"$f":"B3","v":"2009-03-31"},"2010-03-31","2011-03-31","2012-03-31","2013-03-31","2014-03-31","2015-03-31","2016-03-31","2017-03-31","2018-03-31",null,null,null,null,"Cash Adjusted P/E ratio",{"$f":"(Q3-Q4)/Q7","v":17.708778354185739}]
["Operating Cash Flow",{"$f":"'Data Sheet'!B82","v":-2.23},{"$f":"'Data Sheet'!C82","v":18.760000000000002},{"$f":"'Data Sheet'!D82","v":10.07},{"$f":"'Data Sheet'!E82","v":12.54},{"$f":"'Data Sheet'!F82","v":-7.55},{"$f":"'Data Sheet'!G82","v":28.52},{"$f":"'Data Sheet'!H82","v":59.71},{"$f":"'Data Sheet'!I82","v":46.73},{"$f":"'Data Sheet'!J82","v":15.78},{"$f":"'Data Sheet'!K82","v":28.81},null,null,null,null,"Price/Book Value",{"$f":"Q3/(KeyMetrics!K97/'Data Sheet'!B6)","v":5.8542497904442587}]
["Capex",null,{"$f":"('Data Sheet'!C62-'Data Sheet'!B62)+('Data Sheet'!C63-'Data Sheet'!B63)+'Data Sheet'!C26","v":1.0499999999999998},{"$f":"('Data Sheet'!D62-'Data Sheet'!C62)+('Data Sheet'!D63-'Data Sheet'!C63)+'Data Sheet'!D26","v":19.45},{"$f":"('Data Sheet'!E62-'Data Sheet'!D62)+('Data Sheet'!E63-'Data Sheet'!D63)+'Data Sheet'!E26","v":42.9},{"$f":"('Data Sheet'!F62-'Data Sheet'!E62)+('Data Sheet'!F63-'Data Sheet'!E63)+'Data Sheet'!F26","v":77.420000000000016},{"$f":"('Data Sheet'!G62-'Data Sheet'!F62)+('Data Sheet'!G63-'Data Sheet'!F63)+'Data Sheet'!G26","v":25.609999999999978},{"$f":"('Data Sheet'!H62-'Data Sheet'!G62)+('Data Sheet'!H63-'Data Sheet'!G63)+'Data Sheet'!H26","v":13.190000000000014},{"$f":"('Data Sheet'!I62-'Data Sheet'!H62)+('Data Sheet'!I63-'Data Sheet'!H63)+'Data Sheet'!I26","v":14.999999999999996},{"$f":"('Data Sheet'!J62-'Data Sheet'!I62)+('Data Sheet'!J63-'Data Sheet'!I63)+'Data Sheet'!J26","v":12.410000000000002},{"$f":"('Data Sheet'!K62-'Data Sheet'!J62)+('Data Sheet'!K63-'Data Sheet'!J63)+'Data Sheet'!K26","v":39.04},null,null,null,null,"Dividend Yield",{"$f":"Q5/Q3","v":3.6654582109127567E-4}]
["Free Cash Flow",null,{"$f":"C18-C19","v":17.71},{"$f":"D18-D19","v":-9.379999999999999},-30.36,-84.970000000000013,2.9100000000000215,46.519999999999989,31.73,3.3699999999999974,-10.23,null,null,null,null,"Earnings Growth",{"$f":"Q89/Q88-1","v":0.80286081056299285}]
["Tax Rate",{"$f":"'Data Sheet'!B29/'Data Sheet'!B28","v":0.41049030786773094},{"$f":"'Data Sheet'!C29/'Data Sheet'!C28","v":0.33141542002301494},{"$f":"'Data Sheet'!D29/'Data Sheet'!D28","v":0.26650062266500624},{"$f":"'Data Sheet'!E29/'Data Sheet'!E28","v":0.28352769679300294},{"$f":"'Data Sheet'!F29/'Data Sheet'!F28","v":0.32104890148830617},{"$f":"'Data Sheet'!G29/'Data Sheet'!G28","v":0.32956434985034921},{"$f":"'Data Sheet'!H29/'Data Sheet'!H28","v":0.33936745734498541},{"$f":"'Data Sheet'!I29/'Data Sheet'!I28","v":0.34290147401086113},{"$f":"'Data Sheet'!J29/'Data Sheet'!J28","v":0.35021448999046711},{"$f":"'Data Sheet'!K29/'Data Sheet'!K28","v":0.27510691638401419},null,null,null,null,"Inverse PEG ",{"$f":"(Q20+Q19)/Q16","v":4.5225615485483824E-2}]
["NOPLAT",{"$f":"B6*(1-B21)","v":5.6592930444697833},6.137606444188723,6.0880448318804481,10.589460641399418,12.947597448618,31.262414366478215,43.311069496462757,42.579984484096194,62.61982959961869,106.40705574399055]
["RoIC",{"$f":"(B6/B14)*(1-B21)","v":0.12194124207002335},{"$f":"(C6/C14)*(1-C21)","v":0.17357484287864036},0.11918646890917087,0.11631657119287586,6.6947246373412608E-2,0.13885149618688969,0.1937768757391739,0.17963964259417034,0.19858506833989373,0.24948899353807866,null,null,null,null,"Growth Nos:"]
["WACC",0.12,0.12,0.12,0.12,0.12,0.12,0.12,0.12,0.12,0.12,null,null,null,null,"3 Year Sales CAGR ",{"$f":"RATE(3,,-Q58,Q61,0,)","v":0.21874587432400361}]
["EPA (Economic Profit Added)",{"$f":"B14*(B23-B24)","v":9.0093044469784028E-2},{"$f":"C14*(C23-C24)","v":1.8944064441887234},-4.1555168119551865E-2,-0.33533935860058112,-10.260402551382002,4.2444143664782139,16.489869496462759,14.136384484096197,24.780229599618689,55.227055743990547,null,null,null,null,"3 Years Profit CAGR",{"$f":"RATE(3,,-Q86,Q89,0,)","v":0.45753163213180542}]
[null,{"$f":"B3","v":"2009-03-31"},"2010-03-31","2011-03-31","2012-03-31","2013-03-31","2014-03-31","2015-03-31","2016-03-31","2017-03-31","2018-03-31","CURRENT",null,null,null,"1 Year Sales Growth",{"$f":"RATE(1,,-Q60,Q61,0,)","v":0.28105092966855305}]
["MktCap",{"$f":"'Data Sheet'!B90*'Data Sheet'!B93","v":20.114887109067997},{"$f":"'Data Sheet'!C90*'Data Sheet'!C93","v":35.17531846},{"$f":"'Data Sheet'!D90*'Data Sheet'!D93","v":38.014273418749994},{"$f":"'Data Sheet'!E90*'Data Sheet'!E93","v":56.500777813567993},{"$f":"'Data Sheet'!F90*'Data Sheet'!F93","v":54.702527499999995},{"$f":"'Data Sheet'!G90*'Data Sheet'!G93","v":137.88410939408797},{"$f":"'Data Sheet'!H90*'Data Sheet'!H93","v":371.901771865},{"$f":"'Data Sheet'!I90*'Data Sheet'!I93","v":411.44742246581598},{"$f":"'Data Sheet'!J90*'Data Sheet'!J93","v":1272.1851241262759},{"$f":"'Data Sheet'!K90*'Data Sheet'!K93","v":2130.1978551749576},{"$f":"'Data Sheet'!B9","v":1746.03},null,null,null,"1 Year EBIT Growth",{"$f":"RATE(1,,-Q81,Q82,0,)","v":0.33661262395718633}]
["MktCap+Dividend",{"$f":"B27+'Data Sheet'!B31","v":20.534887109067999},{"$f":"C27+'Data Sheet'!C31","v":35.945318460000003},{"$f":"D27+'Data Sheet'!D31","v":38.524273418749992},{"$f":"E27+'Data Sheet'!E31","v":57.010777813567991},{"$f":"F27+'Data Sheet'!F31","v":54.702527499999995},{"$f":"G27+'Data Sheet'!G31","v":138.30410939408796},{"$f":"H27+'Data Sheet'!H31","v":372.54177186499999},{"$f":"I27+'Data Sheet'!I31","v":411.95742246581597},{"$f":"J27+'Data Sheet'!J31","v":1272.825124126276},{"$f":"K27+'Data Sheet'!K31","v":2130.8378551749574},null,null,null,null,"1 Year Profit Growth",{"$f":"RATE(1,,-Q88,Q89,0,)","v":0.80286081056299297}]
["Retained Profit",{"$f":"'Data Sheet'!B30-'Data Sheet'!B31","v":4.75},{"$f":"'Data Sheet'!C30-'Data Sheet'!C31","v":5.0399999999999991},{"$f":"'Data Sheet'!D30-'Data Sheet'!D31","v":5.38},{"$f":"'Data Sheet'!E30-'Data Sheet'!E31","v":9.32},{"$f":"'Data Sheet'!F30-'Data Sheet'!F31","v":9.59},{"$f":"'Data Sheet'!G30-'Data Sheet'!G31","v":19.729999999999997},{"$f":"'Data Sheet'!H30-'Data Sheet'!H31","v":31.11},{"$f":"'Data Sheet'!I30-'Data Sheet'!I31","v":33.370000000000005},{"$f":"'Data Sheet'!J30-'Data Sheet'!J31","v":53.89},{"$f":"'Data Sheet'!K30-'Data Sheet'!K31","v":97.67},null,null,null,null,"RM/ Sales",{"$f":"Q75/Q61","v":0.65829894109777487}]
["Shares Outstanding (Mn)",{"$f":"'Data Sheet'!B70/10^6","v":4.2487399999999997},{"$f":"'Data Sheet'!C70/10^6","v":4.2487399999999997},{"$f":"'Data Sheet'!D70/10^6","v":4.2487399999999997},{"$f":"'Data Sheet'!E70/10^6","v":4.2487399999999997},{"$f":"'Data Sheet'!F70/10^6","v":4.2487399999999997},{"$f":"'Data Sheet'!G70/10^6","v":4.2487399999999997},{"$f":"'Data Sheet'!H70/10^6","v":4.2487399999999997},{"$f":"'Data Sheet'!I70/10^6","v":4.2487399999999997},{"$f":"'Data Sheet'!J70/10^6","v":4.2487399999999997},{"$f":"'Data Sheet'!K70/10^6","v":4.2487399999999997},null,null,null,null,"5 yr Avg RM/Sales",{"$f":"AVERAGE(Q71/Q57,Q72/Q58,Q73/Q59,Q74/Q60,Q75/Q61)","v":0.67025543381638908}]
["EPS",{"$f":"B9/B30*10","v":12.168313429393185},{"$f":"C9/C30*10","v":13.674642364559846},13.862933481455679,23.13627098857544,22.571397637887941,47.42582506813784,74.728037018033589,79.741288005385144,128.34393255412192,231.38624627536637,null,null,null,null,"Inventory/Sales",{"$f":"Q68/Q61","v":0.11885199348756199}]
["EV",{"$f":"B27+'Data Sheet'!B59-'Data Sheet'!B69","v":31.964887109067998},{"$f":"C27+'Data Sheet'!C59-'Data Sheet'!C69","v":36.895318459999999},{"$f":"D27+'Data Sheet'!D59-'Data Sheet'!D69","v":45.374273418749993},{"$f":"E27+'Data Sheet'!E59-'Data Sheet'!E69","v":93.990777813567988},{"$f":"F27+'Data Sheet'!F59-'Data Sheet'!F69","v":181.47252750000001},{"$f":"G27+'Data Sheet'!G59-'Data Sheet'!G69","v":276.21410939408798},{"$f":"H27+'Data Sheet'!H59-'Data Sheet'!H69","v":507.42177186499998},{"$f":"I27+'Data Sheet'!I59-'Data Sheet'!I69","v":518.44742246581598},{"$f":"J27+'Data Sheet'!J59-'Data Sheet'!J69","v":1383.5351241262761},{"$f":"K27+'Data Sheet'!K59-'Data Sheet'!K69","v":2253.5478551749579},null,null,null,null,"5 yr Avg Inventory/Sales",{"$f":"AVERAGE(Q64/Q57,Q65/Q58,Q66/Q59,Q67/Q60,Q68/Q61)","v":0.1536252355956135}]
[null,{"$f":"B3","v":"2009-03-31"},"2010-03-31","2011-03-31","2012-03-31","2013-03-31","2014-03-31","2015-03-31","2016-03-31","2017-03-31","2018-03-31"]
["Price/Earnings",{"$f":"B27/'Data Sheet'!B30","v":3.8906938315411987},{"$f":"C27/'Data Sheet'!C30","v":6.0542716798623069},{"$f":"D27/'Data Sheet'!D30","v":6.4540362340831914},{"$f":"E27/'Data Sheet'!E30","v":5.747790215012003},{"$f":"F27/'Data Sheet'!F30","v":5.7041217413972882},{"$f":"G27/'Data Sheet'!G30","v":6.8428838408976667},{"$f":"H27/'Data Sheet'!H30","v":11.713441633543306},{"$f":"I27/'Data Sheet'!I30","v":12.144256861446751},{"$f":"J27/'Data Sheet'!J30","v":23.330004110146266},{"$f":"K27/'Data Sheet'!K30","v":21.668170635489346},null,null,null,null,"Debt:Equity",{"$f":"Q36/Q35","v":0.43031014249790445}]
["Price/Book",{"$f":"B27/B12","v":0.52836582897473072},0.81822094580134908,0.86909632873228149,1.0674622674016248,0.8748205261474491,1.6778304866644922,3.2870936173325083,2.8104332135643166,6.3384242146693035,7.142323068482674,null,null,null,null,"Networth",{"$f":"Q109","v":298.25}]
["Price/CashFlow",{"$f":"B27/B18","v":-9.0201287484609853},1.8750169754797439,3.7750023255958287,4.5056441637614029,-7.2453678807947011,4.8346461919385684,6.2284671221738401,8.8047811355834789,80.620096585949042,73.939529856819078,null,null,null,null,"Long Term Debt",{"$f":"Q107","v":128.34}]
["Price/Sales",{"$f":"B27/'Data Sheet'!B17","v":0.19540399367658828},{"$f":"C27/'Data Sheet'!C17","v":0.35451842834106029},{"$f":"D27/'Data Sheet'!D17","v":0.40600526987877811},{"$f":"E27/'Data Sheet'!E17","v":0.39803295395257482},{"$f":"F27/'Data Sheet'!F17","v":0.2953859684648199},{"$f":"G27/'Data Sheet'!G17","v":0.38271374873456193},{"$f":"H27/'Data Sheet'!H17","v":0.84969218365738308},{"$f":"I27/'Data Sheet'!I17","v":0.91187567311410656},{"$f":"J27/'Data Sheet'!J17","v":2.056887832055418},{"$f":"K27/'Data Sheet'!K17","v":2.6885235383930399},null,null,null,null,"Cash & Bank Balance",{"$f":"'Data Sheet'!K69","v":4.99}]
["EV/EBITDA",{"$f":"B32/B7","v":3.0356018147263057},3.6675266858846913,4.4880586962166165,5.7311449886321935,6.99316098265896,4.28504668622538,6.0922292215752183,6.3356644563829398,12.265382306084007,13.807657957079579,null,null,null,null,"Investments",{"$f":"'Data Sheet'!K64","v":0.09}]
["Dividend Yield",{"$f":"'Data Sheet'!B31/KeyMetrics!B27","v":2.0880057527673607E-2},{"$f":"'Data Sheet'!C31/KeyMetrics!C27","v":2.1890349077453668E-2},{"$f":"'Data Sheet'!D31/KeyMetrics!D27","v":1.3416013358509961E-2},{"$f":"'Data Sheet'!E31/KeyMetrics!E27","v":9.0264244092853798E-3},{"$f":"'Data Sheet'!F31/KeyMetrics!F27","v":0},{"$f":"'Data Sheet'!G31/KeyMetrics!G27","v":3.0460362825392279E-3},{"$f":"'Data Sheet'!H31/KeyMetrics!H27","v":1.7208845141838136E-3},{"$f":"'Data Sheet'!I31/KeyMetrics!I27","v":1.2395265400948574E-3},{"$f":"'Data Sheet'!J31/KeyMetrics!J27","v":5.0307143816002856E-4},{"$f":"'Data Sheet'!K31/KeyMetrics!K27","v":3.004415756241739E-4}]
[null,{"$f":"B3","v":"2009-03-31"},"2010-03-31","2011-03-31","2012-03-31","2013-03-31","2014-03-31","2015-03-31","2016-03-31","2017-03-31","2018-03-31","Z-Weights",null,null,null,"Management Effectiveness:"]
["Working Capital/Total Assets",{"$f":"B13/B16","v":0.63917043505379689},0.49353448275862072,0.42905561546757054,0.21070605988404412,0.23694469260131573,0.26786411557985162,0.25408467501490761,0.30932866746477583,0.49475760687456083,0.538882717029043,1.2,null,null,null,"Book Value",{"$f":"KeyMetrics!K97/'Data Sheet'!B6","v":701.76370108188291}]
["Retained Profits/Total Assets",{"$f":"B29/B16","v":7.4068298768127247E-2},8.3554376657824919E-2,8.2883993221383456E-2,7.4021126201254867E-2,3.89425810119386E-2,6.4200182220486776E-2,9.2754919499105554E-2,0.10243423274089083,0.14562503377830621,0.19375892715441995,1.4,null,null,null,"ROE",{"$f":"Q7/Q41","v":0.32962279966471081}]
["EBIT/Total Assets",{"$f":"B6/B16","v":0.14969593014189927},0.15218832891246684,0.12786935757202278,0.11738543404018745,7.7438479655648512E-2,0.15173109462449563,0.19546809779367921,0.19891334377014458,0.260417229638437,0.29120377717822565,3.3,null,null,null,"ROCE",{"$f":"Q50/(AVERAGE(Q106,Q107)+AVERAGE(Q108,Q109))","v":0.31708467540868718}]
["Market Cap/Total Liabilities",{"$f":"B27/B16","v":0.31365799328033678},{"$f":"C27/C16","v":0.58314519993368696},0.58564586995455237,0.44873939967888171,0.22213322301632421,0.44866624168322261,1.1088305660852713,1.26299973130066,3.4377806953636596,4.2259122662572564,0.6,null,null,null,"Shares ( in Cr)",{"$f":"'Data Sheet'!B6","v":0.42500060852420707}]
["Sales/Total Assets",{"$f":"'Data Sheet'!B17/KeyMetrics!B16","v":1.6051769842507408},{"$f":"'Data Sheet'!C17/KeyMetrics!C16","v":1.6448938992042441},{"$f":"'Data Sheet'!D17/KeyMetrics!D16","v":1.4424587890925897},{"$f":"'Data Sheet'!E17/KeyMetrics!E16","v":1.127392582003018},{"$f":"'Data Sheet'!F17/KeyMetrics!F16","v":0.75201007065702918},{"$f":"'Data Sheet'!G17/KeyMetrics!G16","v":1.1723285175061824},{"$f":"'Data Sheet'!H17/KeyMetrics!H16","v":1.3049791293977342},{"$f":"'Data Sheet'!I17/KeyMetrics!I16","v":1.3850569420143046},{"$f":"'Data Sheet'!J17/KeyMetrics!J16","v":1.671350591795925},{"$f":"'Data Sheet'!K17/KeyMetrics!K16","v":1.5718338358990638},1,null,null,null,"Margins: "]
["Altman Z-Score",{"$f":"$L$41*B41+$L$42*B42+$L$43*B43+$L$44*B44+$L$45*B45","v":3.1580684900271447},3.2062200112068964,2.8467195201240179,2.1404850026855753,1.4796902318687568,2.3535580685814548,3.0500806890846754,3.3138731420311558,5.3909800423600647,5.9862754187926015,null,null,null,null,"Operating ",{"$f":"Q82/Q61","v":0.21434250880315031}]
["Z > 2.99 -“Safe” Zones",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Net Profit",{"$f":"Q89/Q61","v":0.12407708909166634}]
["1.81 < Z < 2.99 -“Grey” Zones"]
["Z < 1.81 -“Distress” Zones",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Latest Earnings:"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Net Profit (TTM)",{"$f":"SUM(Q51:Q54)","v":117.63999999999999}]
["10 YEARS NUMBERS",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Q1",{"$f":"'Data Sheet'!G49","v":35.520000000000003}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Q2",{"$f":"'Data Sheet'!H49","v":24.98}]
[null,{"$f":"'Profit & Loss'!B3","v":"2009-03-31"},{"$f":"'Profit & Loss'!C3","v":"2010-03-31"},{"$f":"'Profit & Loss'!D3","v":"2011-03-31"},{"$f":"'Profit & Loss'!E3","v":"2012-03-31"},{"$f":"'Profit & Loss'!F3","v":"2013-03-31"},{"$f":"'Profit & Loss'!G3","v":"2014-03-31"},{"$f":"'Profit & Loss'!H3","v":"2015-03-31"},{"$f":"'Profit & Loss'!I3","v":"2016-03-31"},{"$f":"'Profit & Loss'!J3","v":"2017-03-31"},{"$f":"'Profit & Loss'!K3","v":"2018-03-31"},"Total 10 Yrs ","CAGR",null,null,"Q3",{"$f":"'Data Sheet'!I49","v":35.79}]
[{"$f":"'Profit & Loss'!A4","v":"Sales"},{"$f":"'Profit & Loss'!B4","v":102.94},{"$f":"'Profit & Loss'!C4","v":99.22},{"$f":"'Profit & Loss'!D4","v":93.63},{"$f":"'Profit & Loss'!E4","v":141.94999999999999},{"$f":"'Profit & Loss'!F4","v":185.19},{"$f":"'Profit & Loss'!G4","v":360.28},{"$f":"'Profit & Loss'!H4","v":437.69},{"$f":"'Profit & Loss'!I4","v":451.21},{"$f":"'Profit & Loss'!J4","v":618.5},{"$f":"'Profit & Loss'!K4","v":792.33},{"$f":"SUM(B54:K54)","v":3282.9399999999996},{"$f":"RATE(9,,-B54,K54,0,0.2)","v":0.25452758481463006},null,null,"Q4",{"$f":"'Data Sheet'!J49","v":21.35}]
["Receivables",{"$f":"'Data Sheet'!B67","v":22.26},{"$f":"'Data Sheet'!C67","v":16.920000000000002},{"$f":"'Data Sheet'!D67","v":15.93},{"$f":"'Data Sheet'!E67","v":30.04},{"$f":"'Data Sheet'!F67","v":45.02},{"$f":"'Data Sheet'!G67","v":60.41},{"$f":"'Data Sheet'!H67","v":79.53},{"$f":"'Data Sheet'!I67","v":88.17},{"$f":"'Data Sheet'!J67","v":120.15},{"$f":"'Data Sheet'!K67","v":221.61},null,{"$f":"RATE(9,,-B55,K55,0,0.2)","v":0.29091016782631746}]
["% Sales",{"$f":"B55/B54","v":0.21624247134252964},0.17053013505341666,0.17013777635373278,0.21162381120112717,0.24310167935633675,0.16767514155656713,0.18170394571500378,0.19540790319363491,0.1942603071948262,0.27969406686607851,null,null,null,null,"Last 5 Years: Sales"]
["EBITDA",{"$f":"'Profit & Loss'!B6+'Data Sheet'!B26","v":7.3000000000000043},{"$f":"'Profit & Loss'!C6+'Data Sheet'!C26","v":7.2899999999999823},{"$f":"'Profit & Loss'!D6+'Data Sheet'!D26","v":8.3599999999999977},{"$f":"'Profit & Loss'!E6+'Data Sheet'!E26","v":18.30999999999997},{"$f":"'Profit & Loss'!F6+'Data Sheet'!F26","v":32.609999999999992},{"$f":"'Profit & Loss'!G6+'Data Sheet'!G26","v":81.589999999999989},{"$f":"'Profit & Loss'!H6+'Data Sheet'!H26","v":100.13000000000004},{"$f":"'Profit & Loss'!I6+'Data Sheet'!I26","v":98.19999999999996},{"$f":"'Profit & Loss'!J6+'Data Sheet'!J26","v":127.06},{"$f":"'Profit & Loss'!K6+'Data Sheet'!K26","v":169.8300000000001},null,{"$f":"RATE(9,,-B57,K57,0,0.2)","v":0.41858256086031709},null,null,2014,{"$f":"KeyMetrics!G54","v":360.28}]
["EBITDA %",{"$f":"B57/B54","v":7.0915096172527725E-2},7.3473090102801675E-2,8.9287621488839022E-2,0.1289890806622048,0.17608942167503641,0.22646275119351614,0.2287692202243598,0.21763702045610683,0.20543249797898142,0.21434250880315031,null,null,null,null,{"$f":"P57+1","v":2015},{"$f":"KeyMetrics!H54","v":437.69}]
[{"$f":"'Profit & Loss'!A7","v":"Other Income"},{"$f":"'Profit & Loss'!B7","v":4.12},{"$f":"'Profit & Loss'!C7","v":3.65},{"$f":"'Profit & Loss'!D7","v":3.56},{"$f":"'Profit & Loss'!E7","v":-0.28999999999999998},{"$f":"'Profit & Loss'!F7","v":0.18},{"$f":"'Profit & Loss'!G7","v":0.64},{"$f":"'Profit & Loss'!H7","v":0.86},{"$f":"'Profit & Loss'!I7","v":0.6},{"$f":"'Profit & Loss'!J7","v":1.96},{"$f":"'Profit & Loss'!K7","v":9.7899999999999991},null,null,null,null,{"$f":"P58+1","v":2016},{"$f":"KeyMetrics!I54","v":451.21}]
[{"$f":"'Profit & Loss'!A8","v":"Depreciation"},{"$f":"'Profit & Loss'!B8","v":0.93},{"$f":"'Profit & Loss'!C8","v":0.88},{"$f":"'Profit & Loss'!D8","v":1.81},{"$f":"'Profit & Loss'!E8","v":1.62},{"$f":"'Profit & Loss'!F8","v":6.88},{"$f":"'Profit & Loss'!G8","v":17.829999999999998},{"$f":"'Profit & Loss'!H8","v":17.73},{"$f":"'Profit & Loss'!I8","v":17.03},{"$f":"'Profit & Loss'!J8","v":16.43},{"$f":"'Profit & Loss'!K8","v":16.420000000000002},{"$f":"SUM(B60:K60)","v":97.560000000000016},null,null,null,{"$f":"P59+1","v":2017},{"$f":"KeyMetrics!J54","v":618.5}]
[{"$f":"'Profit & Loss'!A9","v":"Interest"},{"$f":"'Profit & Loss'!B9","v":0.83},{"$f":"'Profit & Loss'!C9","v":0.49},{"$f":"'Profit & Loss'!D9","v":0.27},{"$f":"'Profit & Loss'!E9","v":1.06},{"$f":"'Profit & Loss'!F9","v":4.96},{"$f":"'Profit & Loss'!G9","v":16.559999999999999},{"$f":"'Profit & Loss'!H9","v":17.5},{"$f":"'Profit & Loss'!I9","v":13.24},{"$f":"'Profit & Loss'!J9","v":12.45},{"$f":"'Profit & Loss'!K9","v":11.17},{"$f":"SUM(B61:K61)","v":78.53},null,null,null,{"$f":"P60+1","v":2018},{"$f":"KeyMetrics!K54","v":792.33}]
[{"$f":"'Profit & Loss'!A10","v":"Profit before tax"},{"$f":"'Profit & Loss'!B10","v":8.77},{"$f":"'Profit & Loss'!C10","v":8.69},{"$f":"'Profit & Loss'!D10","v":8.0299999999999994},{"$f":"'Profit & Loss'!E10","v":13.72},{"$f":"'Profit & Loss'!F10","v":14.11},{"$f":"'Profit & Loss'!G10","v":30.07},{"$f":"'Profit & Loss'!H10","v":48.06},{"$f":"'Profit & Loss'!I10","v":51.56},{"$f":"'Profit & Loss'!J10","v":83.92},{"$f":"'Profit & Loss'!K10","v":135.62},null,{"$f":"RATE(9,,-B62,K62,0,0.2)","v":0.35564859221955053}]
["Tax%",{"$f":"B64/B62","v":0.41049030786773094},0.33141542002301494,0.26650062266500624,0.28352769679300294,0.32104890148830617,0.32956434985034921,0.33936745734498541,0.34290147401086113,0.35021448999046711,0.27510691638401419,null,null,null,null,"Last 5 Years: Inventory"]
[{"$f":"'Profit & Loss'!A11","v":"Tax"},{"$f":"'Profit & Loss'!B11","v":3.6},{"$f":"'Profit & Loss'!C11","v":2.88},{"$f":"'Profit & Loss'!D11","v":2.14},{"$f":"'Profit & Loss'!E11","v":3.89},{"$f":"'Profit & Loss'!F11","v":4.53},{"$f":"'Profit & Loss'!G11","v":9.91},{"$f":"'Profit & Loss'!H11","v":16.309999999999999},{"$f":"'Profit & Loss'!I11","v":17.68},{"$f":"'Profit & Loss'!J11","v":29.39},{"$f":"'Profit & Loss'!K11","v":37.31},null,null,null,null,{"$f":"P57","v":2014},{"$f":"'Data Sheet'!G68","v":67.430000000000007}]
["Net Profit after Tax",{"$f":"'Profit & Loss'!B12","v":5.17},{"$f":"'Profit & Loss'!C12","v":5.81},{"$f":"'Profit & Loss'!D12","v":5.89},{"$f":"'Profit & Loss'!E12","v":9.83},{"$f":"'Profit & Loss'!F12","v":9.59},{"$f":"'Profit & Loss'!G12","v":20.149999999999999},{"$f":"'Profit & Loss'!H12","v":31.75},{"$f":"'Profit & Loss'!I12","v":33.880000000000003},{"$f":"'Profit & Loss'!J12","v":54.53},{"$f":"'Profit & Loss'!K12","v":98.31},{"$f":"SUM(B65:K65)","v":274.90999999999997},{"$f":"RATE(9,,-B65,K65,0,0.2)","v":0.38714869296180343},null,null,{"$f":"P58","v":2015},{"$f":"'Data Sheet'!H68","v":57.39}]
["NPM%",{"$f":"B65/B54","v":5.0223431124927144E-2},5.855674259221931E-2,6.2907187867136602E-2,6.9249735822472708E-2,5.1784653599006428E-2,5.5928722105029423E-2,7.2539925518060724E-2,7.5086988320294326E-2,8.8164915117219078E-2,0.12407708909166634,null,null,null,null,{"$f":"P59","v":2016},{"$f":"'Data Sheet'!I67","v":88.17}]
["Cash from Operations",{"$f":"'Cash Flow'!B4","v":-2.23},{"$f":"'Cash Flow'!C4","v":18.760000000000002},{"$f":"'Cash Flow'!D4","v":10.07},{"$f":"'Cash Flow'!E4","v":12.54},{"$f":"'Cash Flow'!F4","v":-7.55},{"$f":"'Cash Flow'!G4","v":28.52},{"$f":"'Cash Flow'!H4","v":59.71},{"$f":"'Cash Flow'!I4","v":46.73},{"$f":"'Cash Flow'!J4","v":15.78},{"$f":"'Cash Flow'!K4","v":28.81},{"$f":"SUM(B67:K67)","v":211.14},{"$f":"RATE(9,,-B67,K67,0,0.2)","v":{"$error":"#NUM!"}},null,null,{"$f":"P60","v":2017},{"$f":"'Data Sheet'!J68","v":83.86}]
["Capex(NFA+WIP Change+Dep)",null,{"$f":"('Balance Sheet'!C10-'Balance Sheet'!B10)+('Balance Sheet'!C11-'Balance Sheet'!B11)+C60","v":1.0499999999999998},{"$f":"('Balance Sheet'!D10-'Balance Sheet'!C10)+('Balance Sheet'!D11-'Balance Sheet'!C11)+D60","v":19.45},{"$f":"('Balance Sheet'!E10-'Balance Sheet'!D10)+('Balance Sheet'!E11-'Balance Sheet'!D11)+E60","v":42.9},{"$f":"('Balance Sheet'!F10-'Balance Sheet'!E10)+('Balance Sheet'!F11-'Balance Sheet'!E11)+F60","v":77.420000000000016},{"$f":"('Balance Sheet'!G10-'Balance Sheet'!F10)+('Balance Sheet'!G11-'Balance Sheet'!F11)+G60","v":25.609999999999978},{"$f":"('Balance Sheet'!H10-'Balance Sheet'!G10)+('Balance Sheet'!H11-'Balance Sheet'!G11)+H60","v":13.190000000000014},{"$f":"('Balance Sheet'!I10-'Balance Sheet'!H10)+('Balance Sheet'!I11-'Balance Sheet'!H11)+I60","v":14.999999999999996},{"$f":"('Balance Sheet'!J10-'Balance Sheet'!I10)+('Balance Sheet'!J11-'Balance Sheet'!I11)+J60","v":12.410000000000002},{"$f":"('Balance Sheet'!K10-'Balance Sheet'!J10)+('Balance Sheet'!K11-'Balance Sheet'!J11)+K60","v":39.04},{"$f":"SUM(B68:K68)","v":246.07000000000002},{"$f":"RATE(8,,-C68,K68,0,0.2)","v":0.57141199440462442},null,null,{"$f":"P61","v":2018},{"$f":"'Data Sheet'!K68","v":94.17}]
[null,null,null,null,null,null,null,null,null,null,"FCF",{"$f":"L67-L68","v":-34.930000000000035}]
["YoY Sales Growth (%)",null,{"$f":"C54/B54-1","v":-3.6137555857781223E-2},-5.6339447691997613E-2,0.51607390793549079,0.30461430081014451,0.94546141800313177,0.21486066392805614,3.0889442299344205E-2,0.37075862680348393,0.28105092966855305,null,null,null,null,"Last 5 Years: RM"]
["YoY Op. Profit Growth (%)",null,{"$f":"C57/B57-1","v":-1.3698630137016776E-3},0.14677640603566777,1.1901913875598056,0.78099399235390754,1.5019932536031892,0.22723372962372901,-1.9274942574653675E-2,0.29389002036659928,0.33661262395718627,"Avg Op. Lev",null,null,null,{"$f":"P57","v":2014},{"$f":"'Data Sheet'!G18","v":256.33999999999997}]
["Business Risk (Op. Leverage)",null,{"$f":"C71/C70-1","v":-0.96209309176600788},-3.6052155647332644,1.306242127839913,1.5638782889601557,0.58863516268647365,5.7586463103436403E-2,-1.6239977526257536,-0.20732789712706512,0.1976926187511916,{"$f":"AVERAGE(C72:K72)","v":-0.29828884943454675},null,null,null,{"$f":"P58","v":2015},{"$f":"'Data Sheet'!H18","v":281.08999999999997}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"P59","v":2016},{"$f":"'Data Sheet'!I18","v":293.95}]
["Self Sustainable Growth Rate(SSGR)",null,{"$f":"((1-C82) + C81*C66*(1-'Profit & Loss'!B18)) - 1","v":0.79749691179676319},{"$f":"((1-D82) + D81*D66*(1-'Profit & Loss'!C18)) - 1","v":0.16538333786272919},{"$f":"((1-E82) + E81*E66*(1-'Profit & Loss'!D18)) - 1","v":0.45313088059414408},{"$f":"((1-F82) + F81*F66*(1-'Profit & Loss'!E18)) - 1","v":1.638246337308491E-2},{"$f":"((1-G82) + G81*G66*(1-'Profit & Loss'!F18)) - 1","v":1.6308168142836976E-2},{"$f":"((1-H82) + H81*H66*(1-'Profit & Loss'!G18)) - 1","v":9.777641194190978E-2},{"$f":"((1-I82) + I81*I66*(1-'Profit & Loss'!H18)) - 1","v":0.11912072330481238},{"$f":"((1-J82) + J81*J66*(1-'Profit & Loss'!I18)) - 1","v":0.28450853157721112},{"$f":"((1-K82) + K81*K66*(1-'Profit & Loss'!J18)) - 1","v":0.54654866694584125},null,null,null,null,{"$f":"P60","v":2017},{"$f":"'Data Sheet'!J18","v":425.4}]
["Growth in Sales",null,{"$f":"C54/B54-1","v":-3.6137555857781223E-2},-5.6339447691997613E-2,0.51607390793549079,0.30461430081014451,0.94546141800313177,0.21486066392805614,3.0889442299344205E-2,0.37075862680348393,0.28105092966855305,"Req. Funds ?",null,null,null,{"$f":"P61","v":2018},{"$f":"'Data Sheet'!K18","v":521.59}]
["Need for External Funds (Debt/Equity)",null,{"$f":"IF(C75>C74,\"YES\",\"NO\")","v":"NO"},"NO","YES","YES","YES","YES","NO","YES","NO",{"$f":"IF(COUNTIF(C76:K76,\"YES\")>6,\"Yes\",\"No\")","v":"No"}]
["Return on Invested Capital (ROIC)",{"$f":"KeyMetrics!B23","v":0.12194124207002335},{"$f":"KeyMetrics!C23","v":0.17357484287864036},{"$f":"KeyMetrics!D23","v":0.11918646890917087},{"$f":"KeyMetrics!E23","v":0.11631657119287586},{"$f":"KeyMetrics!F23","v":6.6947246373412608E-2},{"$f":"KeyMetrics!G23","v":0.13885149618688969},{"$f":"KeyMetrics!H23","v":0.1937768757391739},{"$f":"KeyMetrics!I23","v":0.17963964259417034},{"$f":"KeyMetrics!J23","v":0.19858506833989373},{"$f":"KeyMetrics!K23","v":0.24948899353807866},null,null,null,null,"Last 5 Years: EBIT"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"P57","v":2014},{"$f":"KeyMetrics!G57","v":81.589999999999989}]
[null,{"$f":"B53","v":"2009-03-31"},"2010-03-31","2011-03-31","2012-03-31","2013-03-31","2014-03-31","2015-03-31","2016-03-31","2017-03-31","2018-03-31",null,null,null,null,{"$f":"P58","v":2015},{"$f":"KeyMetrics!H57","v":100.13000000000004}]
["Capital Intensity (EBITDA / EBIT)",{"$f":"(B57)/(B57-B60)","v":1.1459968602825745},1.1372854914196571,1.2763358778625957,1.0970641102456564,1.2673921492421298,1.2796424090338772,1.2151699029126213,1.2098065787852657,1.14851306155654,1.1070334398018382,null,null,null,null,{"$f":"P59","v":2016},{"$f":"KeyMetrics!I57","v":98.19999999999996}]
["Net Fixed Assets Turns (Higher is better)",{"$f":"'Profit & Loss'!B4/'Balance Sheet'!B10","v":18.992619926199261},{"$f":"'Profit & Loss'!C4/'Balance Sheet'!C10","v":17.749552772808588},{"$f":"'Profit & Loss'!D4/'Balance Sheet'!D10","v":4.693233082706767},{"$f":"'Profit & Loss'!E4/'Balance Sheet'!E10","v":8.7407635467980302},{"$f":"'Profit & Loss'!F4/'Balance Sheet'!F10","v":1.3712699000370232},{"$f":"'Profit & Loss'!G4/'Balance Sheet'!G10","v":2.5325460424574722},{"$f":"'Profit & Loss'!H4/'Balance Sheet'!H10","v":3.2037037037037037},{"$f":"'Profit & Loss'!I4/'Balance Sheet'!I10","v":3.3245652814618332},{"$f":"'Profit & Loss'!J4/'Balance Sheet'!J10","v":4.7202930626574062},{"$f":"'Profit & Loss'!K4/'Balance Sheet'!K10","v":5.3637286758732738},null,null,null,null,{"$f":"P60","v":2017},{"$f":"KeyMetrics!J57","v":127.06}]
["Depreciation/NFA (consistency)",{"$f":"B60/'Balance Sheet'!B10","v":0.17158671586715868},{"$f":"C60/'Balance Sheet'!C10","v":0.15742397137745975},{"$f":"D60/'Balance Sheet'!D10","v":9.0726817042606517E-2},{"$f":"E60/'Balance Sheet'!E10","v":9.9753694581280805E-2},{"$f":"F60/'Balance Sheet'!F10","v":5.0944094779711215E-2},{"$f":"G60/'Balance Sheet'!G10","v":0.12533389568395895},{"$f":"H60/'Balance Sheet'!H10","v":0.1297760210803689},{"$f":"I60/'Balance Sheet'!I10","v":0.12547892720306514},{"$f":"J60/'Balance Sheet'!J10","v":0.12539113180187744},{"$f":"K60/'Balance Sheet'!K10","v":0.11115624153804496},null,null,null,null,{"$f":"P61","v":2018},{"$f":"KeyMetrics!K57","v":169.8300000000001}]
["Receivable days (Lower is better)",{"$f":"'Balance Sheet'!B22","v":78.928502040023318},{"$f":"'Balance Sheet'!C22","v":62.243499294497077},{"$f":"'Balance Sheet'!D22","v":62.100288369112469},{"$f":"'Balance Sheet'!E22","v":77.242691088411405},{"$f":"'Balance Sheet'!F22","v":88.732112965062925},{"$f":"'Balance Sheet'!G22","v":61.201426668146993},{"$f":"'Balance Sheet'!H22","v":66.321940185976374},{"$f":"'Balance Sheet'!I22","v":71.323884665676729},{"$f":"'Balance Sheet'!J22","v":70.905012126111558},{"$f":"'Balance Sheet'!K22","v":102.08833440611866}]
["Inventory Turnover (Higher is better)",{"$f":"'Balance Sheet'!B20","v":9.1583629893238427},{"$f":"'Balance Sheet'!C20","v":7.3063328424153164},{"$f":"'Balance Sheet'!D20","v":7.9213197969543145},{"$f":"'Balance Sheet'!E20","v":8.4949132256134039},{"$f":"'Balance Sheet'!F20","v":4.9702093397745575},{"$f":"'Balance Sheet'!G20","v":5.3430223935933547},{"$f":"'Balance Sheet'!H20","v":7.6265899982575363},{"$f":"'Balance Sheet'!I20","v":7.9508370044052858},{"$f":"'Balance Sheet'!J20","v":7.3753875506797044},{"$f":"'Balance Sheet'!K20","v":8.4138260592545393},null,null,null,null,"Last 5 Years: Profits"]
["Working Capital Cycle",{"$f":"'Balance Sheet'!B22+'Balance Sheet'!B21","v":118.78278608898387},{"$f":"'Balance Sheet'!C22+'Balance Sheet'!C21","v":112.20016125781092},{"$f":"'Balance Sheet'!D22+'Balance Sheet'!D21","v":108.17846843960271},{"$f":"'Balance Sheet'!E22+'Balance Sheet'!E21","v":120.20958083832335},{"$f":"'Balance Sheet'!F22+'Balance Sheet'!F21","v":162.16966358874672},{"$f":"'Balance Sheet'!G22+'Balance Sheet'!G21","v":129.51482180526259},{"$f":"'Balance Sheet'!H22+'Balance Sheet'!H21","v":114.18081290411021},{"$f":"'Balance Sheet'!I22+'Balance Sheet'!I21","v":117.23100108596884},{"$f":"'Balance Sheet'!J22+'Balance Sheet'!J21","v":120.39393694421989},{"$f":"'Balance Sheet'!K22+'Balance Sheet'!K21","v":145.46931202907879},null,null,null,null,{"$f":"P57","v":2014},{"$f":"KeyMetrics!G65","v":20.149999999999999}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"P58","v":2015},{"$f":"KeyMetrics!H65","v":31.75}]
["Net Fixed Assets",{"$f":"'Balance Sheet'!B10","v":5.42},{"$f":"'Balance Sheet'!C10","v":5.59},{"$f":"'Balance Sheet'!D10","v":19.95},{"$f":"'Balance Sheet'!E10","v":16.239999999999998},{"$f":"'Balance Sheet'!F10","v":135.05000000000001},{"$f":"'Balance Sheet'!G10","v":142.26},{"$f":"'Balance Sheet'!H10","v":136.62},{"$f":"'Balance Sheet'!I10","v":135.72},{"$f":"'Balance Sheet'!J10","v":131.03},{"$f":"'Balance Sheet'!K10","v":147.72},null,null,null,null,{"$f":"P59","v":2016},{"$f":"KeyMetrics!I65","v":33.880000000000003}]
["CWIP",{"$f":"'Balance Sheet'!B11","v":0},{"$f":"'Balance Sheet'!C11","v":0},{"$f":"'Balance Sheet'!D11","v":3.28},{"$f":"'Balance Sheet'!E11","v":48.27},{"$f":"'Balance Sheet'!F11","v":0},{"$f":"'Balance Sheet'!G11","v":0.56999999999999995},{"$f":"'Balance Sheet'!H11","v":1.67},{"$f":"'Balance Sheet'!I11","v":0.54},{"$f":"'Balance Sheet'!J11","v":1.21},{"$f":"'Balance Sheet'!K11","v":7.14},null,null,null,null,{"$f":"P60","v":2017},{"$f":"KeyMetrics!J65","v":54.53}]
["Share Capital",{"$f":"'Balance Sheet'!B4","v":4.25},{"$f":"'Balance Sheet'!C4","v":4.25},{"$f":"'Balance Sheet'!D4","v":4.25},{"$f":"'Balance Sheet'!E4","v":4.25},{"$f":"'Balance Sheet'!F4","v":4.25},{"$f":"'Balance Sheet'!G4","v":4.25},{"$f":"'Balance Sheet'!H4","v":4.25},{"$f":"'Balance Sheet'!I4","v":4.25},{"$f":"'Balance Sheet'!J4","v":4.25},{"$f":"'Balance Sheet'!K4","v":4.25},null,null,null,null,{"$f":"P61","v":2018},{"$f":"KeyMetrics!K65","v":98.31}]
[]
["Dividend Paid (Div) without DDT",{"$f":"'Data Sheet'!B31","v":0.42},{"$f":"'Data Sheet'!C31","v":0.77},{"$f":"'Data Sheet'!D31","v":0.51},{"$f":"'Data Sheet'!E31","v":0.51},{"$f":"'Data Sheet'!F31","v":0},{"$f":"'Data Sheet'!G31","v":0.42},{"$f":"'Data Sheet'!H31","v":0.64},{"$f":"'Data Sheet'!I31","v":0.51},{"$f":"'Data Sheet'!J31","v":0.64},{"$f":"'Data Sheet'!K31","v":0.64},null,null,null,null,"Last 5 Years: Dividends"]
["Dividend Payout (Div/PAT)",{"$f":"B91/B65","v":8.1237911025145063E-2},0.13253012048192772,8.6587436332767415E-2,5.188199389623601E-2,0,2.0843672456575684E-2,2.0157480314960629E-2,1.5053128689492325E-2,1.1736658719970658E-2,6.5100193266198758E-3,null,null,null,null,{"$f":"P57","v":2014},{"$f":"'Data Sheet'!G31","v":0.42}]
["Retained Earnings (PAT-Div)",{"$f":"B65-B91","v":4.75},5.0399999999999991,5.38,9.32,9.59,19.729999999999997,31.11,33.370000000000005,53.89,97.67,{"$f":"SUM(B93:K93)","v":269.85000000000002},null,null,null,{"$f":"P58","v":2015},{"$f":"'Data Sheet'!H31","v":0.64}]
["Cash + Investments (CI+NCI)",{"$f":"'Data Sheet'!B69+'Data Sheet'!B64","v":5.25},{"$f":"'Data Sheet'!C69+'Data Sheet'!C64","v":13.49},{"$f":"'Data Sheet'!D69+'Data Sheet'!D64","v":2.2000000000000002},{"$f":"'Data Sheet'!E69+'Data Sheet'!E64","v":2.6},{"$f":"'Data Sheet'!F69+'Data Sheet'!F64","v":4.66},{"$f":"'Data Sheet'!G69+'Data Sheet'!G64","v":5.16},{"$f":"'Data Sheet'!H69+'Data Sheet'!H64","v":34.43},{"$f":"'Data Sheet'!I69+'Data Sheet'!I64","v":23.91},{"$f":"'Data Sheet'!J69+'Data Sheet'!J64","v":3.4499999999999997},{"$f":"'Data Sheet'!K69+'Data Sheet'!K64","v":5.08},null,null,null,null,{"$f":"P59","v":2016},{"$f":"'Data Sheet'!I31","v":0.51}]
[null,{"$f":"B53","v":"2009-03-31"},"2010-03-31","2011-03-31","2012-03-31","2013-03-31","2014-03-31","2015-03-31","2016-03-31","2017-03-31","2018-03-31",null,null,null,null,{"$f":"P60","v":2017},{"$f":"'Data Sheet'!J31","v":0.64}]
["Total Debt(D)",{"$f":"'Balance Sheet'!B6","v":12.72},{"$f":"'Balance Sheet'!C6","v":3.79},{"$f":"'Balance Sheet'!D6","v":8.4499999999999993},{"$f":"'Balance Sheet'!E6","v":39.1},{"$f":"'Balance Sheet'!F6","v":131.15},{"$f":"'Balance Sheet'!G6","v":143.22999999999999},{"$f":"'Balance Sheet'!H6","v":140.16},{"$f":"'Balance Sheet'!I6","v":110.77},{"$f":"'Balance Sheet'!J6","v":114.71},{"$f":"'Balance Sheet'!K6","v":128.34},null,null,null,null,{"$f":"P61","v":2018},{"$f":"'Data Sheet'!K31","v":0.64}]
["Total Equity(E)",{"$f":"'Balance Sheet'!B4+'Balance Sheet'!B5","v":38.07},{"$f":"'Balance Sheet'!C4+'Balance Sheet'!C5","v":42.99},{"$f":"'Balance Sheet'!D4+'Balance Sheet'!D5","v":43.74},{"$f":"'Balance Sheet'!E4+'Balance Sheet'!E5","v":52.93},{"$f":"'Balance Sheet'!F4+'Balance Sheet'!F5","v":62.53},{"$f":"'Balance Sheet'!G4+'Balance Sheet'!G5","v":82.18},{"$f":"'Balance Sheet'!H4+'Balance Sheet'!H5","v":113.14},{"$f":"'Balance Sheet'!I4+'Balance Sheet'!I5","v":146.4},{"$f":"'Balance Sheet'!J4+'Balance Sheet'!J5","v":200.71},{"$f":"'Balance Sheet'!K4+'Balance Sheet'!K5","v":298.25}]
["D/E",{"$f":"B96/B97","v":0.33412135539795118},8.8160037217957662E-2,0.19318701417466846,0.73871150576232758,2.0973932512394051,1.7428814796787537,1.2388191621000531,0.75662568306010924,0.57152110009466384,0.43031014249790445,null,null,null,null,"Last 5 Years: Op CF"]
["Cost of Funds",0.12,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"P57","v":2014},{"$f":"KeyMetrics!G104","v":28.52}]
["Interest Outgo (Rs Cr) (Calculated)",{"$f":"$B$99*B96","v":1.5264},0.45479999999999998,1.0139999999999998,4.6920000000000002,15.738,17.1876,16.819199999999999,13.292399999999999,13.765199999999998,15.4008,{"$f":"SUM(B100:K100)","v":99.8904},null,null,null,{"$f":"P58","v":2015},{"$f":"KeyMetrics!H104","v":59.71}]
["Interest Coverage (Op/Int. Outgo)",{"$f":"B57/B100","v":4.7824947589098565},16.02902374670181,8.2445759368836278,3.9023870417732245,2.0720548989706438,4.7470269263887914,5.9533152587519051,7.3876801781469084,9.2305233487344918,11.027349228611508,null,null,null,null,{"$f":"P59","v":2016},{"$f":"KeyMetrics!I104","v":46.73}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"P60","v":2017},{"$f":"KeyMetrics!J104","v":15.78}]
[null,{"$f":"'Cash Flow'!B3","v":"2009-03-31"},{"$f":"'Cash Flow'!C3","v":"2010-03-31"},{"$f":"'Cash Flow'!D3","v":"2011-03-31"},{"$f":"'Cash Flow'!E3","v":"2012-03-31"},{"$f":"'Cash Flow'!F3","v":"2013-03-31"},{"$f":"'Cash Flow'!G3","v":"2014-03-31"},{"$f":"'Cash Flow'!H3","v":"2015-03-31"},{"$f":"'Cash Flow'!I3","v":"2016-03-31"},{"$f":"'Cash Flow'!J3","v":"2017-03-31"},{"$f":"'Cash Flow'!K3","v":"2018-03-31"},"Total 10 Yrs ",null,null,null,{"$f":"P61","v":2018},{"$f":"KeyMetrics!K104","v":28.81}]
[{"$f":"'Cash Flow'!A4","v":"Cash from Operating Activity"},{"$f":"'Cash Flow'!B4","v":-2.23},{"$f":"'Cash Flow'!C4","v":18.760000000000002},{"$f":"'Cash Flow'!D4","v":10.07},{"$f":"'Cash Flow'!E4","v":12.54},{"$f":"'Cash Flow'!F4","v":-7.55},{"$f":"'Cash Flow'!G4","v":28.52},{"$f":"'Cash Flow'!H4","v":59.71},{"$f":"'Cash Flow'!I4","v":46.73},{"$f":"'Cash Flow'!J4","v":15.78},{"$f":"'Cash Flow'!K4","v":28.81},{"$f":"SUM(B104:K104)","v":211.14}]
[{"$f":"'Cash Flow'!A5","v":"Cash from Investing Activity"},{"$f":"'Cash Flow'!B5","v":-3.99},{"$f":"'Cash Flow'!C5","v":-8.0500000000000007},{"$f":"'Cash Flow'!D5","v":-6.93},{"$f":"'Cash Flow'!E5","v":-41.81},{"$f":"'Cash Flow'!F5","v":-76.69},{"$f":"'Cash Flow'!G5","v":-25.36},{"$f":"'Cash Flow'!H5","v":-40.97},{"$f":"'Cash Flow'!I5","v":-4.99},{"$f":"'Cash Flow'!J5","v":7.77},{"$f":"'Cash Flow'!K5","v":-30.85},{"$f":"SUM(B105:K105)","v":-231.86999999999998},null,null,null,"Debt: Equity"]
[{"$f":"'Cash Flow'!A6","v":"Cash from Financing Activity"},{"$f":"'Cash Flow'!B6","v":4.8600000000000003},{"$f":"'Cash Flow'!C6","v":-9.6199999999999992},{"$f":"'Cash Flow'!D6","v":-5.23},{"$f":"'Cash Flow'!E6","v":29.79},{"$f":"'Cash Flow'!F6","v":87.01},{"$f":"'Cash Flow'!G6","v":-2.65},{"$f":"'Cash Flow'!H6","v":-18.98},{"$f":"'Cash Flow'!I6","v":-42.62},{"$f":"'Cash Flow'!J6","v":-23.9},{"$f":"'Cash Flow'!K6","v":2.23},{"$f":"SUM(B106:K106)","v":20.889999999999997},null,null,null,{"$f":"CONCATENATE(\"Debt FY\",P102)","v":"Debt FY2017"},{"$f":"KeyMetrics!J96","v":114.71}]
[{"$f":"'Cash Flow'!A7","v":"Net Cash Flow"},{"$f":"'Cash Flow'!B7","v":-1.36},{"$f":"'Cash Flow'!C7","v":1.0900000000000001},{"$f":"'Cash Flow'!D7","v":-2.09},{"$f":"'Cash Flow'!E7","v":0.52},{"$f":"'Cash Flow'!F7","v":2.77},{"$f":"'Cash Flow'!G7","v":0.51},{"$f":"'Cash Flow'!H7","v":-0.25},{"$f":"'Cash Flow'!I7","v":-0.88},{"$f":"'Cash Flow'!J7","v":-0.34},{"$f":"'Cash Flow'!K7","v":0.18},{"$f":"SUM(B107:K107)","v":0.15000000000000013},null,null,null,{"$f":"CONCATENATE(\"Debt FY\",P103)","v":"Debt FY2018"},{"$f":"KeyMetrics!K96","v":128.34}]
["Cash & Eq at end of Year",{"$f":"'Data Sheet'!B69","v":0.87},{"$f":"'Data Sheet'!C69","v":2.0699999999999998},{"$f":"'Data Sheet'!D69","v":1.0900000000000001},{"$f":"'Data Sheet'!E69","v":1.61},{"$f":"'Data Sheet'!F69","v":4.38},{"$f":"'Data Sheet'!G69","v":4.9000000000000004},{"$f":"'Data Sheet'!H69","v":4.6399999999999997},{"$f":"'Data Sheet'!I69","v":3.77},{"$f":"'Data Sheet'!J69","v":3.36},{"$f":"'Data Sheet'!K69","v":4.99},null,null,null,null,{"$f":"CONCATENATE(\"Equity FY\",P102)","v":"Equity FY2017"},{"$f":"KeyMetrics!J97","v":200.71}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"CONCATENATE(\"Equity FY\",P103)","v":"Equity FY2018"},{"$f":"KeyMetrics!K97","v":298.25}]
["Market Cap",{"$f":"'Data Sheet'!B90*'Data Sheet'!B93","v":20.114887109067997},{"$f":"'Data Sheet'!C90*'Data Sheet'!C93","v":35.17531846},{"$f":"'Data Sheet'!D90*'Data Sheet'!D93","v":38.014273418749994},{"$f":"'Data Sheet'!E90*'Data Sheet'!E93","v":56.500777813567993},{"$f":"'Data Sheet'!F90*'Data Sheet'!F93","v":54.702527499999995},{"$f":"'Data Sheet'!G90*'Data Sheet'!G93","v":137.88410939408797},{"$f":"'Data Sheet'!H90*'Data Sheet'!H93","v":371.901771865},{"$f":"'Data Sheet'!I90*'Data Sheet'!I93","v":411.44742246581598},{"$f":"'Data Sheet'!J90*'Data Sheet'!J93","v":1272.1851241262759},{"$f":"'Data Sheet'!K90*'Data Sheet'!K93","v":2130.1978551749576}]
["P/B",{"$f":"B110/B97","v":0.52836582897473072},{"$f":"C110/C97","v":0.81822094580134908},0.86909632873228149,1.0674622674016248,0.8748205261474491,1.6778304866644922,3.2870936173325083,2.8104332135643166,6.3384242146693035,7.142323068482674]

{"sheet":"Charts","index":7,"n_rows":12,"n_cols":23,"rows_kept":12,"cut":false,"hidden":false,"merged":[[0,0,0,1],[9,15,9,16],[10,15,10,16],[11,15,11,16],[9,19,9,21],[10,19,10,21],[11,19,11,21]]}
[{"$f":"'Data Sheet'!B1","v":"BHARAT RASAYAN LTD"}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"KeyMetrics!F53","v":"2013-03-31"},{"$f":"KeyMetrics!G53","v":"2014-03-31"},{"$f":"KeyMetrics!H53","v":"2015-03-31"},{"$f":"KeyMetrics!I53","v":"2016-03-31"},{"$f":"KeyMetrics!J53","v":"2017-03-31"},{"$f":"KeyMetrics!K53","v":"2018-03-31"},"Growth (x)"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Sales (INR Cr)",{"$f":"KeyMetrics!F54","v":185.19},{"$f":"KeyMetrics!G54","v":360.28},{"$f":"KeyMetrics!H54","v":437.69},{"$f":"KeyMetrics!I54","v":451.21},{"$f":"KeyMetrics!J54","v":618.5},{"$f":"KeyMetrics!K54","v":792.33},{"$f":"V3/Q3","v":4.2784707597602463}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"PAT (INR Cr)",{"$f":"KeyMetrics!F65","v":9.59},{"$f":"KeyMetrics!G65","v":20.149999999999999},{"$f":"KeyMetrics!H65","v":31.75},{"$f":"KeyMetrics!I65","v":33.880000000000003},{"$f":"KeyMetrics!J65","v":54.53},{"$f":"KeyMetrics!K65","v":98.31},{"$f":"V4/Q4","v":10.251303441084463}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"ROE (%)",{"$f":"Q4/KeyMetrics!F97","v":0.1533663841356149},{"$f":"R4/KeyMetrics!G97","v":0.24519347773180819},{"$f":"S4/KeyMetrics!H97","v":0.28062577337811562},{"$f":"T4/KeyMetrics!I97","v":0.23142076502732242},{"$f":"U4/KeyMetrics!J97","v":0.27168551641672062},{"$f":"V4/KeyMetrics!K97","v":0.32962279966471081},2.1492506426521758]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"PE (x)",{"$f":"Q8/Q4","v":5.7041217413972882},6.8428838408976667,11.713441633543306,12.144256861446751,23.330004110146266,21.668170635489346,3.7986865669843657]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"PB (x)",{"$f":"KeyMetrics!F111","v":0.8748205261474491},{"$f":"KeyMetrics!G111","v":1.6778304866644922},{"$f":"KeyMetrics!H111","v":3.2870936173325083},{"$f":"KeyMetrics!I111","v":2.8104332135643166},{"$f":"KeyMetrics!J111","v":6.3384242146693035},{"$f":"KeyMetrics!K111","v":7.142323068482674},8.1643295453253355]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Mcap (INR Cr)",{"$f":"KeyMetrics!F110","v":54.702527499999995},{"$f":"KeyMetrics!G110","v":137.88410939408797},{"$f":"KeyMetrics!H110","v":371.901771865},{"$f":"KeyMetrics!I110","v":411.44742246581598},{"$f":"KeyMetrics!J110","v":1272.1851241262759},{"$f":"KeyMetrics!K110","v":2130.1978551749576},38.941488675728152]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"10 Years","3 Years","Total Retained Earnings (10 Yrs)",null,null,{"$f":"KeyMetrics!L93","v":269.85000000000002}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"OCF as part of Sales",null,{"$f":"KeyMetrics!L104/KeyMetrics!L54","v":6.4314303642466819E-2},{"$f":"SUM(KeyMetrics!I104:K104)/SUM(KeyMetrics!I54:K54)","v":4.9042985113101754E-2},"Total Mcap Increase (10 Yrs)",null,null,{"$f":"Customization!C5","v":2110.0829680658894}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"OCF as part of Profits",null,{"$f":"KeyMetrics!L104/KeyMetrics!L65","v":0.76803317449347064},{"$f":"SUM(KeyMetrics!I104:K104)/SUM(KeyMetrics!I65:K65)","v":0.48907455012853468},"Value created per INR of RE",null,null,{"$f":"W11/W10","v":7.8194662518654408}]

{"sheet":"Forecast","index":8,"n_rows":39,"n_cols":19,"rows_kept":39,"cut":false,"hidden":false,"merged":[]}
[null,"Annual"]
[null,"Growth%",null,{"$f":"D10/C10-1","v":-3.6137555857781223E-2},-5.6339447691997613E-2,0.51607390793549079,0.30461430081014451,0.94546141800313177,0.21486066392805614,3.0889442299344205E-2,0.37075862680348393,0.28105092966855305,0.15,0.15,{"$f":"MEDIAN(L2:N2)","v":0.15},{"$f":"MEDIAN(M2:O2)","v":0.15},{"$f":"MEDIAN(N2:P2)","v":0.15}]
[null,"Exp as Sales%",{"$f":"C11/C10","v":0.93811929279191753},0.93539608949808528,0.93004378938374455,0.88242338851708368,0.86106161239807766,0.82302653491728661,0.81173890196257614,0.82010593736840942,0.8211317704122878,0.806381179559022,0.89,{"$f":"1-N4","v":0.88800000000000001},{"$f":"1-O4","v":0.88700000000000001},{"$f":"1-P4","v":0.88600000000000001},{"$f":"1-Q4","v":0.88500000000000001}]
[null,"OPM %",{"$f":"C12/C10","v":6.1880707208082426E-2},6.460391050191476E-2,6.995621061625544E-2,0.11757661148291632,0.13893838760192229,0.17697346508271344,0.18826109803742383,0.17989406263159052,0.1788682295877122,0.19361882044097797,0.11,0.112,0.113,0.114,0.115]
[null,"Tax %",{"$f":"C17/C16","v":0.41049030786773094},0.33141542002301494,0.26650062266500624,0.28352769679300294,0.32104890148830617,0.32956434985034921,0.33936745734498541,0.34290147401086113,0.35021448999046711,0.27510691638401419,0.35,0.35,0.35,0.35,0.35]
[null,"NPM %",{"$f":"C18/C10","v":5.0223431124927144E-2},{"$f":"D18/D10","v":5.855674259221931E-2},6.2907187867136602E-2,6.9249735822472708E-2,5.1784653599006428E-2,5.5928722105029423E-2,7.2539925518060724E-2,7.5086988320294326E-2,8.8164915117219078E-2,0.12407708909166634,5.7930802053821458E-2,6.0912070076776015E-2,6.2980447682235222E-2,6.4333887792487374E-2,6.5635157273303116E-2]
[]
[]
[null,"Narration",{"$f":"'Profit & Loss'!B3","v":"2009-03-31"},{"$f":"'Profit & Loss'!C3","v":"2010-03-31"},{"$f":"'Profit & Loss'!D3","v":"2011-03-31"},{"$f":"'Profit & Loss'!E3","v":"2012-03-31"},{"$f":"'Profit & Loss'!F3","v":"2013-03-31"},{"$f":"'Profit & Loss'!G3","v":"2014-03-31"},{"$f":"'Profit & Loss'!H3","v":"2015-03-31"},{"$f":"'Profit & Loss'!I3","v":"2016-03-31"},{"$f":"'Profit & Loss'!J3","v":"2017-03-31"},{"$f":"'Profit & Loss'!K3","v":"2018-03-31"},{"$f":"L9+365","v":"2019-03-31"},{"$f":"M9+365","v":"2020-03-30"},"2021-03-30","2022-03-30","2023-03-30",null,"5 Yr Cagr"]
[null,"Sales",{"$f":"'Profit & Loss'!B4","v":102.94},{"$f":"'Profit & Loss'!C4","v":99.22},{"$f":"'Profit & Loss'!D4","v":93.63},{"$f":"'Profit & Loss'!E4","v":141.94999999999999},{"$f":"'Profit & Loss'!F4","v":185.19},{"$f":"'Profit & Loss'!G4","v":360.28},{"$f":"'Profit & Loss'!H4","v":437.69},{"$f":"'Profit & Loss'!I4","v":451.21},{"$f":"'Profit & Loss'!J4","v":618.5},{"$f":"'Profit & Loss'!K4","v":792.33},{"$f":"L10*(1+M2)","v":911.17949999999996},{"$f":"M10*(1+N2)","v":1047.8564249999999},1205.0348887499999,1385.7901220624999,1593.6586403718748,null,{"$f":"RATE(5,,-L10,Q10,1,)","v":0.14999999999516303}]
[null,"Expenses",{"$f":"'Profit & Loss'!B5","v":96.57},{"$f":"'Profit & Loss'!C5","v":92.810000000000016},{"$f":"'Profit & Loss'!D5","v":87.08},{"$f":"'Profit & Loss'!E5","v":125.26000000000002},{"$f":"'Profit & Loss'!F5","v":159.46},{"$f":"'Profit & Loss'!G5","v":296.52},{"$f":"'Profit & Loss'!H5","v":355.28999999999996},{"$f":"'Profit & Loss'!I5","v":370.04},{"$f":"'Profit & Loss'!J5","v":507.87},{"$f":"'Profit & Loss'!K5","v":638.91999999999996},{"$f":"M10-M12","v":810.94975499999998},{"$f":"N10-N12","v":930.49650539999993},1068.86594632125,1227.8100481473748,1410.3878967291091,null,{"$f":"RATE(5,,-L11,Q11,1,)","v":0.17159745032520754}]
[null,"Operating Profit",{"$f":"'Profit & Loss'!B6","v":6.3700000000000045},{"$f":"'Profit & Loss'!C6","v":6.4099999999999824},{"$f":"'Profit & Loss'!D6","v":6.5499999999999972},{"$f":"'Profit & Loss'!E6","v":16.689999999999969},{"$f":"'Profit & Loss'!F6","v":25.72999999999999},{"$f":"'Profit & Loss'!G6","v":63.759999999999991},{"$f":"'Profit & Loss'!H6","v":82.400000000000034},{"$f":"'Profit & Loss'!I6","v":81.169999999999959},{"$f":"'Profit & Loss'!J6","v":110.63},{"$f":"'Profit & Loss'!K6","v":153.41000000000008},{"$f":"M4*M10","v":100.22974499999999},{"$f":"N4*N10","v":117.3599196},136.16894242875,157.98007391512499,183.27074364276561,null,3.6210275032340422E-2]
[null,"Other Income",{"$f":"'Profit & Loss'!B7","v":4.12},{"$f":"'Profit & Loss'!C7","v":3.65},{"$f":"'Profit & Loss'!D7","v":3.56},{"$f":"'Profit & Loss'!E7","v":-0.28999999999999998},{"$f":"'Profit & Loss'!F7","v":0.18},{"$f":"'Profit & Loss'!G7","v":0.64},{"$f":"'Profit & Loss'!H7","v":0.86},{"$f":"'Profit & Loss'!I7","v":0.6},{"$f":"'Profit & Loss'!J7","v":1.96},{"$f":"'Profit & Loss'!K7","v":9.7899999999999991},{"$f":"L13*1.1","v":10.769},{"$f":"M13*1.1","v":11.8459},13.030490000000002,14.333539000000004,15.766892900000006,null,9.9999999999998992E-2]
[null,"Depreciation",{"$f":"'Profit & Loss'!B8","v":0.93},{"$f":"'Profit & Loss'!C8","v":0.88},{"$f":"'Profit & Loss'!D8","v":1.81},{"$f":"'Profit & Loss'!E8","v":1.62},{"$f":"'Profit & Loss'!F8","v":6.88},{"$f":"'Profit & Loss'!G8","v":17.829999999999998},{"$f":"'Profit & Loss'!H8","v":17.73},{"$f":"'Profit & Loss'!I8","v":17.03},{"$f":"'Profit & Loss'!J8","v":16.43},{"$f":"'Profit & Loss'!K8","v":16.420000000000002},{"$f":"L14*1.1","v":18.062000000000005},19.868200000000005,21.855020000000007,24.04052200000001,26.444574200000012,null,9.999999999999909E-2]
[null,"Interest",{"$f":"'Profit & Loss'!B9","v":0.83},{"$f":"'Profit & Loss'!C9","v":0.49},{"$f":"'Profit & Loss'!D9","v":0.27},{"$f":"'Profit & Loss'!E9","v":1.06},{"$f":"'Profit & Loss'!F9","v":4.96},{"$f":"'Profit & Loss'!G9","v":16.559999999999999},{"$f":"'Profit & Loss'!H9","v":17.5},{"$f":"'Profit & Loss'!I9","v":13.24},{"$f":"'Profit & Loss'!J9","v":12.45},{"$f":"'Profit & Loss'!K9","v":11.17},{"$f":"L15*1.05","v":11.7285},{"$f":"M15*0.95","v":11.142075},{"$f":"N15*0.95","v":10.584971249999999},{"$f":"O15*1.05","v":11.1142198125},11.669930803125,null,8.7952335100219409E-3]
[null,"Profit before tax",{"$f":"'Profit & Loss'!B10","v":8.77},{"$f":"'Profit & Loss'!C10","v":8.69},{"$f":"'Profit & Loss'!D10","v":8.0299999999999994},{"$f":"'Profit & Loss'!E10","v":13.72},{"$f":"'Profit & Loss'!F10","v":14.11},{"$f":"'Profit & Loss'!G10","v":30.07},{"$f":"'Profit & Loss'!H10","v":48.06},{"$f":"'Profit & Loss'!I10","v":51.56},{"$f":"'Profit & Loss'!J10","v":83.92},{"$f":"'Profit & Loss'!K10","v":135.62},{"$f":"M12+M13-M14-M15","v":81.208245000000005},{"$f":"N12+N13-N14-N15","v":98.195544599999977},116.75944117875001,137.15887110262497,160.92313153964062,null,{"$f":"RATE(5,,-L16,Q16,1,)","v":3.4806021149150587E-2}]
[null,"Tax",{"$f":"'Profit & Loss'!B11","v":3.6},{"$f":"'Profit & Loss'!C11","v":2.88},{"$f":"'Profit & Loss'!D11","v":2.14},{"$f":"'Profit & Loss'!E11","v":3.89},{"$f":"'Profit & Loss'!F11","v":4.53},{"$f":"'Profit & Loss'!G11","v":9.91},{"$f":"'Profit & Loss'!H11","v":16.309999999999999},{"$f":"'Profit & Loss'!I11","v":17.68},{"$f":"'Profit & Loss'!J11","v":29.39},{"$f":"'Profit & Loss'!K11","v":37.31},{"$f":"M16*M5","v":28.422885749999999},{"$f":"N16*N5","v":34.368440609999986},40.865804412562504,48.005604885918736,56.323096038874212,null,8.58560467378994E-2]
[null,"Net profit",{"$f":"'Profit & Loss'!B12","v":5.17},{"$f":"'Profit & Loss'!C12","v":5.81},{"$f":"'Profit & Loss'!D12","v":5.89},{"$f":"'Profit & Loss'!E12","v":9.83},{"$f":"'Profit & Loss'!F12","v":9.59},{"$f":"'Profit & Loss'!G12","v":20.149999999999999},{"$f":"'Profit & Loss'!H12","v":31.75},{"$f":"'Profit & Loss'!I12","v":33.880000000000003},{"$f":"'Profit & Loss'!J12","v":54.53},{"$f":"'Profit & Loss'!K12","v":98.31},{"$f":"M16-M17","v":52.785359250000006},{"$f":"N16-N17","v":63.827103989999991},75.893636766187512,89.153266216706243,104.60003550076641,null,1.2480871960857691E-2]
[null,"EPS",{"$f":"'Profit & Loss'!B13","v":12.168313429393185},{"$f":"'Profit & Loss'!C13","v":13.674642364559846},{"$f":"'Profit & Loss'!D13","v":13.862933481455679},{"$f":"'Profit & Loss'!E13","v":23.13627098857544},{"$f":"'Profit & Loss'!F13","v":22.571397637887941},{"$f":"'Profit & Loss'!G13","v":47.425825068137847},{"$f":"'Profit & Loss'!H13","v":74.728037018033589},{"$f":"'Profit & Loss'!I13","v":79.741288005385144},{"$f":"'Profit & Loss'!J13","v":128.34393255412195},{"$f":"'Profit & Loss'!K13","v":231.38624627536637},{"$f":"M18/$M$23","v":124.20066746091135},{"$f":"N18/$M$23","v":150.18120612023677},178.57300729456435,209.77209074190839,246.1173781938447,null,1.2420540759337647E-2]
[null,"Price to earning",{"$f":"'Profit & Loss'!B14","v":3.8906938315411987},{"$f":"'Profit & Loss'!C14","v":6.0542716798623069},{"$f":"'Profit & Loss'!D14","v":6.4540362340831914},{"$f":"'Profit & Loss'!E14","v":5.747790215012003},{"$f":"'Profit & Loss'!F14","v":5.7041217413972882},{"$f":"'Profit & Loss'!G14","v":6.8428838408976675},{"$f":"'Profit & Loss'!H14","v":11.713441633543306},{"$f":"'Profit & Loss'!I14","v":12.144256861446751},{"$f":"'Profit & Loss'!J14","v":23.330004110146266},{"$f":"'Profit & Loss'!K14","v":21.668170635489346},{"$f":"M21/M19","v":33.07792207552324},20,20,20,20]
[null,"Price",{"$f":"'Profit & Loss'!B15","v":47.343181999999999},{"$f":"'Profit & Loss'!C15","v":82.79},{"$f":"'Profit & Loss'!D15","v":89.471874999999997},{"$f":"'Profit & Loss'!E15","v":132.98243199999999},{"$f":"'Profit & Loss'!F15","v":128.75},{"$f":"'Profit & Loss'!G15","v":324.52941199999998},{"$f":"'Profit & Loss'!H15","v":875.32249999999999},{"$f":"'Profit & Loss'!I15","v":968.398684},{"$f":"'Profit & Loss'!J15","v":2994.2644740000001},{"$f":"'Profit & Loss'!K15","v":5013.7166669999997},{"$f":"'Profit & Loss'!L15","v":4108.3},{"$f":"N20*N19","v":3003.6241224047353},{"$f":"O20*O19","v":3571.4601458912871},4195.4418148381674,4922.3475638768941,null,-3.6716282142117088E-3]
[]
[null,null,null,null,null,null,null,null,null,null,null,"Nosh",{"$f":"'Data Sheet'!B6","v":0.42500060852420707}]
[null,"Quarterly"]
[null,"QoQ Sales",null,{"$f":"D29/C29-1","v":1.8132923549750268E-2},{"$f":"E29/D29-1","v":0.27650743340125294},0.44286136565178835,-0.22699336228796196,2.5336584331601797E-2,0.26716294458229939,0.16379732375979095,-0.33550671293861956,0.43611521418020693,0.3]
[null,"Tax %",null,{"$f":"D36/D35","v":0.38308711156393277},{"$f":"E36/E35","v":0.34161752316764954},0.36930330015715035,0.3470022624434389,7.3794002607561929E-2,0.29988789237668162,0.2991971803407088,0.30749270191372041,0.21698615548455805,{"$f":"MEDIAN(I26:L26)","v":0.29954253635869521}]
[null,"Quarterly","Contribution",{"$f":"D29/$K$10","v":0.2142441390460792},{"$f":"E29/$K$10","v":0.27348423605497174},0.39459983831851253,0.3050282942603072,{"$f":"H29/$L$10","v":0.24414069895119456},{"$f":"I29/$L$10","v":0.3093660469753764},0.36003937753208887,0.23924374944783108]
[null,"Narration",{"$f":"Quarters!B3","v":"2016-12-31"},{"$f":"Quarters!C3","v":"2017-03-31"},{"$f":"Quarters!D3","v":"2017-06-30"},{"$f":"Quarters!E3","v":"2017-09-30"},{"$f":"Quarters!F3","v":"2017-12-31"},{"$f":"Quarters!G3","v":"2018-03-31"},{"$f":"Quarters!H3","v":"2018-06-30"},{"$f":"Quarters!I3","v":"2018-09-30"},{"$f":"Quarters!J3","v":"2018-12-31"},{"$f":"Quarters!K3","v":"2019-03-31"},{"$f":"L28+90","v":"2019-06-29"},"YoY","QoQ"]
[null,"Sales",{"$f":"Quarters!B4","v":130.15},{"$f":"Quarters!C4","v":132.51},{"$f":"Quarters!D4","v":169.15},{"$f":"Quarters!E4","v":244.06},{"$f":"Quarters!F4","v":188.66},{"$f":"Quarters!G4","v":193.44},{"$f":"Quarters!H4","v":245.12},{"$f":"Quarters!I4","v":285.27},{"$f":"Quarters!J4","v":189.56},{"$f":"Quarters!K4","v":272.23},{"$f":"L29*(1+M25)","v":353.89900000000006},{"$f":"L29/H29-1","v":0.40730976013234099},{"$f":"L29/K29-1","v":0.43611521418020693}]
[null,"Expenses",{"$f":"Quarters!B5","v":107.56},{"$f":"Quarters!C5","v":101.01},{"$f":"Quarters!D5","v":139.41},{"$f":"Quarters!E5","v":198.74},{"$f":"Quarters!F5","v":143.77000000000001},{"$f":"Quarters!G5","v":155.19999999999999},{"$f":"Quarters!H5","v":204.1},{"$f":"Quarters!I5","v":226.5},{"$f":"Quarters!J5","v":150.13},{"$f":"Quarters!K5","v":224.35},{"$f":"M29-M31","v":280.28517023633685},{"$f":"L30/H30-1","v":0.44555412371134029},{"$f":"L30/K30-1","v":0.49437154466129352}]
[null,"Operating Profit",{"$f":"Quarters!B6","v":22.59},{"$f":"Quarters!C6","v":31.5},{"$f":"Quarters!D6","v":29.74},{"$f":"Quarters!E6","v":45.32},{"$f":"Quarters!F6","v":44.89},{"$f":"Quarters!G6","v":38.24},{"$f":"Quarters!H6","v":41.02},{"$f":"Quarters!I6","v":58.77},{"$f":"Quarters!J6","v":39.43},{"$f":"Quarters!K6","v":47.88},{"$f":"M29*M39","v":73.613829763663233},0.252092050209205,0.21430382957139238]
[null,"Other Income",{"$f":"Quarters!B7","v":2.5},{"$f":"Quarters!C7","v":-5.12},{"$f":"Quarters!D7","v":0.68},{"$f":"Quarters!E7","v":-0.18},{"$f":"Quarters!F7","v":-2.62},{"$f":"Quarters!G7","v":6.62},{"$f":"Quarters!H7","v":1.78},{"$f":"Quarters!I7","v":0.56000000000000005},{"$f":"Quarters!J7","v":-0.12},{"$f":"Quarters!K7","v":-1.47},{"$f":"AVERAGE(I32:L32)","v":0.18749999999999994},-1.2220543806646527,11.25]
[null,"Depreciation",{"$f":"Quarters!B8","v":4.0999999999999996},{"$f":"Quarters!C8","v":4.29},{"$f":"Quarters!D8","v":3.88},{"$f":"Quarters!E8","v":4.03},{"$f":"Quarters!F8","v":4.18},{"$f":"Quarters!G8","v":4.33},{"$f":"Quarters!H8","v":4.03},{"$f":"Quarters!I8","v":4.25},{"$f":"Quarters!J8","v":4.3499999999999996},{"$f":"Quarters!K8","v":4.26},{"$f":"I33*1.32","v":5.3196000000000003},-1.616628175519641E-2,-2.0689655172413723E-2]
[null,"Interest",{"$f":"Quarters!B9","v":3.99},{"$f":"Quarters!C9","v":2.46},{"$f":"Quarters!D9","v":2.8},{"$f":"Quarters!E9","v":2.93},{"$f":"Quarters!F9","v":2.73},{"$f":"Quarters!G9","v":2.1800000000000002},{"$f":"Quarters!H9","v":3.09},{"$f":"Quarters!I9","v":4.01},{"$f":"Quarters!J9","v":4.13},{"$f":"Quarters!K9","v":4.59},8,1.1055045871559632,0.11138014527845042]
[null,"Profit before tax",{"$f":"Quarters!B10","v":17},{"$f":"Quarters!C10","v":19.63},{"$f":"Quarters!D10","v":23.74},{"$f":"Quarters!E10","v":38.18},{"$f":"Quarters!F10","v":35.36},{"$f":"Quarters!G10","v":38.35},{"$f":"Quarters!H10","v":35.68},{"$f":"Quarters!I10","v":51.07},{"$f":"Quarters!J10","v":30.83},{"$f":"Quarters!K10","v":37.56},{"$f":"M31+M32-M33-M34","v":60.481729763663239},-2.059973924380698E-2,0.21829386960752517]
[null,"Tax",{"$f":"Quarters!B11","v":5.76},{"$f":"Quarters!C11","v":7.52},{"$f":"Quarters!D11","v":8.11},{"$f":"Quarters!E11","v":14.1},{"$f":"Quarters!F11","v":12.27},{"$f":"Quarters!G11","v":2.83},{"$f":"Quarters!H11","v":10.7},{"$f":"Quarters!I11","v":15.28},{"$f":"Quarters!J11","v":9.48},{"$f":"Quarters!K11","v":8.15},{"$f":"M26*M35","v":18.116850736768875},1.8798586572438163,-0.14029535864978904]
[null,"Net profit",{"$f":"Quarters!B12","v":11.24},{"$f":"Quarters!C12","v":12.11},{"$f":"Quarters!D12","v":15.63},{"$f":"Quarters!E12","v":24.08},{"$f":"Quarters!F12","v":23.09},{"$f":"Quarters!G12","v":35.520000000000003},{"$f":"Quarters!H12","v":24.98},{"$f":"Quarters!I12","v":35.79},{"$f":"Quarters!J12","v":21.35},{"$f":"Quarters!K12","v":29.41},{"$f":"M35-M36","v":42.364879026894364},-0.17201576576576583,0.37751756440281015]
[null,null,{"$f":"Quarters!B13","v":0},{"$f":"Quarters!C13","v":0},{"$f":"Quarters!D13","v":0},{"$f":"Quarters!E13","v":0},{"$f":"Quarters!F13","v":0},{"$f":"Quarters!G13","v":0},{"$f":"Quarters!H13","v":0},{"$f":"Quarters!I13","v":0},{"$f":"Quarters!J13","v":0},{"$f":"Quarters!K13","v":0}]
[null,"OPM",{"$f":"Quarters!B14","v":0.17356895889358431},{"$f":"Quarters!C14","v":0.23771790808240889},{"$f":"Quarters!D14","v":0.17582027785988766},{"$f":"Quarters!E14","v":0.18569204294026059},{"$f":"Quarters!F14","v":0.23794127000954099},{"$f":"Quarters!G14","v":0.19768403639371382},{"$f":"Quarters!H14","v":0.16734660574412533},{"$f":"Quarters!I14","v":0.20601535387527609},{"$f":"Quarters!J14","v":0.20800801856931841},{"$f":"Quarters!K14","v":0.1758806891231679},{"$f":"K39","v":0.20800801856931841},-0.1102939198748536,-0.15445236038073273]